{"id":4836,"date":"2010-11-15T08:00:00","date_gmt":"2010-11-15T10:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-502\/"},"modified":"2015-11-12T16:41:18","modified_gmt":"2015-11-12T18:41:18","slug":"erramos-502","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-502\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>&#8220;Ongs investigadas por supostas irregularidades continuam a receber dinheiro  da Uni\u00e3o nos \u00faltimos dois anos&#8221;, escrevemos na p\u00e1g. 2. Ops! A regra diz que se  escreve com todas as letras grandonas a sigla que tem at\u00e9 tr\u00eas letras ou a que  as letras se pronunciam uma a uma. \u00c9 caso de ONG e tamb\u00e9m de UTI, PM, OEA,  PIBINSS, BNDES, FGTS. O plural? Basta um esse pequenino: <i>ONGs, PMs, UTIs,  PIBs.<\/i>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Ongs investigadas por supostas irregularidades continuam a receber dinheiro da Uni\u00e3o nos \u00faltimos dois anos&#8221;, escrevemos na p\u00e1g. 2. Ops! A regra diz que se escreve com todas as letras grandonas a sigla que tem at\u00e9 tr\u00eas letras ou a que as letras se pronunciam uma a uma. \u00c9 caso de ONG e tamb\u00e9m de UTI, PM, OEA, PIBINSS, BNDES, FGTS. O plural? Basta um [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-4836","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4836"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4836\/revisions"}],"predecessor-version":[{"id":10361,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4836\/revisions\/10361"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}