{"id":4795,"date":"2010-07-15T16:00:00","date_gmt":"2010-07-15T19:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-492\/"},"modified":"2015-11-12T16:49:22","modified_gmt":"2015-11-12T18:49:22","slug":"erramos-492","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-492\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>&#8220;O Eca e o caso Bruno&#8221; \u00e9 o t\u00edtulo de artigo publicado na p\u00e1g. 22. Viu? Baita  trope\u00e7o na grafia. A sigla com at\u00e9 tr\u00eas letras escreve-se com as letras  mai\u00fasculas (OEA, UTI, PM). \u00c9 o caso de ECA \u2014 Estatuto da Crian\u00e7a e do  Adolescente.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O Eca e o caso Bruno&#8221; \u00e9 o t\u00edtulo de artigo publicado na p\u00e1g. 22. Viu? Baita trope\u00e7o na grafia. A sigla com at\u00e9 tr\u00eas letras escreve-se com as letras mai\u00fasculas (OEA, UTI, PM). \u00c9 o caso de ECA \u2014 Estatuto da Crian\u00e7a e do Adolescente.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-4795","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4795"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4795\/revisions"}],"predecessor-version":[{"id":10589,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4795\/revisions\/10589"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}