{"id":4786,"date":"2010-07-14T18:00:00","date_gmt":"2010-07-14T21:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-489\/"},"modified":"2015-11-12T16:49:23","modified_gmt":"2015-11-12T18:49:23","slug":"erramos-489","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-489\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>&#8220;Tenho a sensa\u00e7\u00e3o de que todos os nova-iorquinos, n\u00e3o importa o que eles  fa\u00e7am, est\u00e3o em suas pr\u00f3prias s\u00e9ries de tev\u00ea, com seus pr\u00f3prios temas musicais,  e voc\u00ea \u00e9 um mero convidado do show deles&#8221;, escrevemos na p\u00e1g. 10 do <i>Divers\u00e3o  &amp; Arte<\/i>. Seus pr\u00f3prios? \u00c9 redund\u00e2ncia. Al\u00e9m disso, o texto pede  lipoaspira\u00e7\u00e3o. Assim: Tenho a sensa\u00e7\u00e3o de que os nova-iorquinos, n\u00e3o importa o  que fa\u00e7am, est\u00e3o nas pr\u00f3prias s\u00e9ries de tev\u00ea, com os pr\u00f3prios temas musicais, e  voc\u00ea \u00e9 mero convidado do show deles.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Tenho a sensa\u00e7\u00e3o de que todos os nova-iorquinos, n\u00e3o importa o que eles fa\u00e7am, est\u00e3o em suas pr\u00f3prias s\u00e9ries de tev\u00ea, com seus pr\u00f3prios temas musicais, e voc\u00ea \u00e9 um mero convidado do show deles&#8221;, escrevemos na p\u00e1g. 10 do Divers\u00e3o &amp; Arte. Seus pr\u00f3prios? \u00c9 redund\u00e2ncia. Al\u00e9m disso, o texto pede lipoaspira\u00e7\u00e3o. Assim: Tenho a sensa\u00e7\u00e3o de que os nova-iorquinos, n\u00e3o importa o que [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-4786","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4786"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4786\/revisions"}],"predecessor-version":[{"id":10590,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4786\/revisions\/10590"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}