{"id":4719,"date":"2010-10-31T00:01:00","date_gmt":"2010-10-31T02:01:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/segredo_e_pra_quatro_paredes\/"},"modified":"2010-10-31T00:01:00","modified_gmt":"2010-10-31T02:01:00","slug":"segredo_e_pra_quatro_paredes","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/segredo_e_pra_quatro_paredes\/","title":{"rendered":"Segredo \u00e9 pra quatro paredes"},"content":{"rendered":"<p>  <BR>&nbsp; &nbsp; Ufa! \u00c9 hoje. N\u00e3o faltaram propagandas. Os candidatos fizeram promessas pra dar, empresar, alugar e vender. Apresentaram-se embalados para presente. Qual deles o eleitor comprar\u00e1? S\u00f3 ele sabe. Dono e senhor da resposta, o brasileiro responder\u00e1 na urna. Sozinho, digitar\u00e1 o n\u00famero do escolhido. <BR> &nbsp; Da\u00ed o nome \u2014 voto secreto. O adjetivo vem do latim secretus. Na l\u00edngua dos C\u00e9sares, a triss\u00edlaba quer dizer separada, ilhada, escondida. Na de Cam\u00f5es, Pessoa, Machado e Jo\u00e3o Cabral, nomeia ilustre fam\u00edlia. Entre seus membros, figura a palavra secret\u00e1ria.  <BR> &nbsp; A hist\u00f3ria come\u00e7ou assim. Quando usava fraldas, secretarius era lugar retirado, sala de reuni\u00f5es de ju\u00edzes, tribunal secreto. Mais tarde, tomou outro rumo. Deu nome a pessoa a quem se confiam segredos. Chefes preferem entregar a fun\u00e7\u00e3o a mulher. Por qu\u00ea? Talvez por acreditarem mais no sexo oposto. \u00c0s vezes se arrependem. Quando ela d\u00e1 com a l\u00edngua nos dentes, valha-nos, Deus! Sai de baixo. <BR>&nbsp; <BR><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Ufa! \u00c9 hoje. N\u00e3o faltaram propagandas. Os candidatos fizeram promessas pra dar, empresar, alugar e vender. Apresentaram-se embalados para presente. Qual deles o eleitor comprar\u00e1? S\u00f3 ele sabe. Dono e senhor da resposta, o brasileiro responder\u00e1 na urna. Sozinho, digitar\u00e1 o n\u00famero do escolhido. &nbsp; Da\u00ed o nome \u2014 voto secreto. O adjetivo vem do latim secretus. Na l\u00edngua dos C\u00e9sares, a triss\u00edlaba [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4719","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4719"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4719\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}