{"id":4636,"date":"2010-07-01T10:00:00","date_gmt":"2010-07-01T13:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/mata-mata\/"},"modified":"2010-07-01T10:00:00","modified_gmt":"2010-07-01T13:00:00","slug":"mata-mata","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/mata-mata\/","title":{"rendered":"Mata-mata"},"content":{"rendered":"\n<p>Que med\u00e3o! As regras da Fifa s\u00e3o cru\u00e9is. Quem  perde volta pra casa. \u00c9 o mata-mata. Qual o plural da duplinha? Ela joga no time  de reco-reco, tico-tico, troca-troca, quebra-quebra, pisca-pisca, tique-taque.  Os dois elementos s\u00e3o constitu\u00eddos de palavras iguais ou indicam som de coisa.  No caso, s\u00f3 o \u00faltimo se flexiona. O primeiro fica na sombra regada com \u00e1gua  fresca: <i>reco-recos, tico-ticos, troca-trocas, quebra-quebras, pisca-piscas,  tique-taques. E, claro, mata-matas.<\/i><b>  <\/p>\n<p><\/b>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que med\u00e3o! As regras da Fifa s\u00e3o cru\u00e9is. Quem perde volta pra casa. \u00c9 o mata-mata. Qual o plural da duplinha? Ela joga no time de reco-reco, tico-tico, troca-troca, quebra-quebra, pisca-pisca, tique-taque. Os dois elementos s\u00e3o constitu\u00eddos de palavras iguais ou indicam som de coisa. No caso, s\u00f3 o \u00faltimo se flexiona. O primeiro fica na sombra regada com \u00e1gua fresca: reco-recos, tico-ticos, troca-trocas, quebra-quebras, [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4636","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4636"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4636\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}