{"id":4517,"date":"2010-06-18T00:00:00","date_gmt":"2010-06-18T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/pergunta_de_leitor-2\/"},"modified":"2015-11-13T10:39:52","modified_gmt":"2015-11-13T12:39:52","slug":"pergunta_de_leitor-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/pergunta_de_leitor-2\/","title":{"rendered":"Pergunta de leitor"},"content":{"rendered":"<p><B><\/B>&nbsp; <B><\/B>&nbsp; Muitos est\u00e3o usando uma constru\u00e7\u00e3o de frase esquisita. Eis exemplos: &#8220;Ele vir\u00e1 a Bras\u00edlia faz\u00ea um curso t\u00e9cnico&#8221; (em vez de fazer). &#8220;O amigo viajou muito para vir me v\u00ea&#8221; (em vez de ver). &#8220;No pr\u00f3ximo ano ele vai curs\u00e1 uma faculdade&#8221; (em vez de cursar). Estranho, n\u00e3o? A l\u00edngua mudou? (\u00c1lvaro Sampaio Filho0 &nbsp; A confus\u00e3o, \u00c1lvaro, \u00e9 muito mais comum do que voc\u00ea imagina. A causa prov\u00e1vel: pouca familiaridade com a l\u00edngua escrita. A pessoa ouve o verbo sem o <B>r<\/B> final. Escreve-o do mesmo jeitinho. Como n\u00e3o cair na esparrela? \u00c9 f\u00e1cil como tirar doce de crian\u00e7a. <I><\/I> <I><\/I>&nbsp; <I>Fazer, ver, cursar<\/I> s\u00e3o formas do infinitivo. Por detestar a solid\u00e3o, o infinitivo, em geral, vem acompanhado de auxiliar. \u00c9 o caso, n\u00e3o? Ele vir\u00e1 a Bras\u00edlia fazer um curso t\u00e9cnico (vir\u00e1 fazer). O amigo viajou para vir me ver (vir ver). No pr\u00f3ximo ano ele vai cursar uma faculdade. &nbsp; <BR><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Muitos est\u00e3o usando uma constru\u00e7\u00e3o de frase esquisita. Eis exemplos: &#8220;Ele vir\u00e1 a Bras\u00edlia faz\u00ea um curso t\u00e9cnico&#8221; (em vez de fazer). &#8220;O amigo viajou muito para vir me v\u00ea&#8221; (em vez de ver). &#8220;No pr\u00f3ximo ano ele vai curs\u00e1 uma faculdade&#8221; (em vez de cursar). Estranho, n\u00e3o? A l\u00edngua mudou? (\u00c1lvaro Sampaio Filho0 &nbsp; A confus\u00e3o, \u00c1lvaro, \u00e9 muito mais comum do [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-4517","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4517"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4517\/revisions"}],"predecessor-version":[{"id":11465,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4517\/revisions\/11465"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}