{"id":4516,"date":"2010-10-13T16:30:00","date_gmt":"2010-10-13T19:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-448\/"},"modified":"2015-11-12T16:43:21","modified_gmt":"2015-11-12T18:43:21","slug":"erramos-448-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-448-2\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>O leitor  Telmo Ghiorzi escreve: &#8220;\u00c9 batata! D\u00ea a um rep\u00f3rter ou redator de qualquer  jornal brasileiro a escolha entre os voc\u00e1bulos mal e mau ou infringir e  infligir. Eles erram todas. Parece praga. Hoje foi o <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">Correio<\/b> na p\u00e1gina 23  (mal funcionamento intestinal). Se serve de consolo, n\u00e3o \u00e9 s\u00f3 o <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">Correio<\/b>  que erra todas. A <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">Folha<\/i> tamb\u00e9m n\u00e3o acerta uma&#8221;. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O leitor Telmo Ghiorzi escreve: &#8220;\u00c9 batata! D\u00ea a um rep\u00f3rter ou redator de qualquer jornal brasileiro a escolha entre os voc\u00e1bulos mal e mau ou infringir e infligir. Eles erram todas. Parece praga. Hoje foi o Correio na p\u00e1gina 23 (mal funcionamento intestinal). Se serve de consolo, n\u00e3o \u00e9 s\u00f3 o Correio que erra todas. A Folha tamb\u00e9m n\u00e3o acerta uma&#8221;.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-4516","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4516"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4516\/revisions"}],"predecessor-version":[{"id":10431,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4516\/revisions\/10431"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}