{"id":4505,"date":"2010-06-16T00:00:00","date_gmt":"2010-06-16T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/duvida_de_leitor-2\/"},"modified":"2010-06-16T00:00:00","modified_gmt":"2010-06-16T03:00:00","slug":"duvida_de_leitor-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/duvida_de_leitor-2\/","title":{"rendered":"D\u00favida de leitor"},"content":{"rendered":"<p>&nbsp; &nbsp; Ao entrar no site de uma franquia, li a propaganda deles sobre &#8220;a inovadora postura de franquiados que traziam para Bras\u00edlia&#8221;. Uma d\u00favida enoooorme passou a atormentar-me desde ent\u00e3o: franqueado? Franquiado? (Maria C\u00e9lia) &nbsp; Maria C\u00e9lia, o dicion\u00e1rio s\u00f3 registra franqueado. O usu\u00e1rio da franquia \u00e9 franqueado, com e. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Ao entrar no site de uma franquia, li a propaganda deles sobre &#8220;a inovadora postura de franquiados que traziam para Bras\u00edlia&#8221;. Uma d\u00favida enoooorme passou a atormentar-me desde ent\u00e3o: franqueado? Franquiado? (Maria C\u00e9lia) &nbsp; Maria C\u00e9lia, o dicion\u00e1rio s\u00f3 registra franqueado. O usu\u00e1rio da franquia \u00e9 franqueado, com e.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4505","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4505"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4505\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}