{"id":443,"date":"2015-06-05T19:00:00","date_gmt":"2015-06-05T19:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/06\/05\/erramos-91\/"},"modified":"2015-11-12T12:10:52","modified_gmt":"2015-11-12T14:10:52","slug":"erramos-91","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-91\/","title":{"rendered":"Erramos"},"content":{"rendered":"<p>&#8220;O  militar, que foi ex-ministro do Ex\u00e9rcito e ex-chefe do DOI-Codi, morreu ontem  aos 94 anos&#8221;, escrevemos na capa.  Viu? Maltratamos outra vez o ex. Le\u00f4nidas n\u00e3o foi ex-ministro nem ex-chefe. Ele  foi ministro e chefe. Melhor: <i>O militar, que foi ministro do Ex\u00e9rcito e chefe  do DOI-Codi, morreu ontem aos 94 anos. <\/i>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O militar, que foi ex-ministro do Ex\u00e9rcito e ex-chefe do DOI-Codi, morreu ontem aos 94 anos&#8221;, escrevemos na capa. Viu? Maltratamos outra vez o ex. Le\u00f4nidas n\u00e3o foi ex-ministro nem ex-chefe. Ele foi ministro e chefe. Melhor: O militar, que foi ministro do Ex\u00e9rcito e chefe do DOI-Codi, morreu ontem aos 94 anos.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-443","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=443"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/443\/revisions"}],"predecessor-version":[{"id":1007,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/443\/revisions\/1007"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}