{"id":441,"date":"2015-06-05T00:00:00","date_gmt":"2015-06-05T00:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/06\/05\/sem_excecao\/"},"modified":"2015-10-23T16:56:06","modified_gmt":"2015-10-23T18:56:06","slug":"sem_excecao","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/sem_excecao\/","title":{"rendered":"Sem exce\u00e7\u00e3o"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/b> A grafia de infravermelho quebrou a cabe\u00e7a da meninada da UnB. Uns juravam  que a palavra se escrevia com h\u00edfen. Outros, que as duas partes deveriam ficar  juntinhas. E da\u00ed? Consultada a gram\u00e1tica, a turma aprendeu a li\u00e7\u00e3o.     <i> <\/p>\n<p><\/i><i>Infra<\/i> pertence \u00e0 equipe da maior parte dos prefixos. Pede o tracinho  quando seguido de <b>h<\/b> ou de vogais iguais. No mais, \u00e9 tudo colado:      <i>infra-hep\u00e1tico, infra-humano, infra-ac\u00fastico, infra-at\u00f4mico, infra-axilar,  infraconstitucional, infravermelho.<\/i>    &nbsp;<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/b> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A grafia de infravermelho quebrou a cabe\u00e7a da meninada da UnB. Uns juravam que a palavra se escrevia com h\u00edfen. Outros, que as duas partes deveriam ficar juntinhas. E da\u00ed? Consultada a gram\u00e1tica, a turma aprendeu a li\u00e7\u00e3o. Infra pertence \u00e0 equipe da maior parte dos prefixos. Pede o tracinho quando seguido de h ou de vogais iguais. No mais, \u00e9 tudo colado: infra-hep\u00e1tico, infra-humano, [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-441","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=441"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/441\/revisions"}],"predecessor-version":[{"id":1011,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/441\/revisions\/1011"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}