{"id":428,"date":"2015-06-01T00:00:00","date_gmt":"2015-06-01T00:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/06\/01\/diquinhas_infantis_51\/"},"modified":"2015-11-12T19:33:41","modified_gmt":"2015-11-12T21:33:41","slug":"diquinhas_infantis_51","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/diquinhas_infantis_51\/","title":{"rendered":"Diquinhas infantis 51"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <strong> <\/p>\n<p><\/strong><strong>Vit\u00f3ria-r\u00e9gia, uma hist\u00f3ria de  amor<\/strong>  <\/p>\n<p>Quando o mundo nasceu, a Lua era guerreiro pra l\u00e1 de  valente. Ela iluminava a Terra noite ap\u00f3s noite. Com a claridade, encontrava as  \u00edndias bonitas e as transformava em estrelas do c\u00e9u.  <\/p>\n<p>Nai\u00e1 sonhava ser escolhida. Banhava-se todos os dias sob a  luz do luar. Mas a Lua n\u00e3o a via. Ia, ent\u00e3o, para o alto da montanha pra ser  vista. Em v\u00e3o. Uma noite, Nai\u00e1 viu a Lua refletida na \u00e1gua.   <\/p>\n<p>Pensou que o astro tivesse descido at\u00e9 a Terra. Atirou-se na  \u00e1gua. Morreu. Em sinal de gratid\u00e3o por t\u00e3o grande amor, Nai\u00e1 virou a imensa e  bela vit\u00f3ria-r\u00e9gia. A Lua a abra\u00e7a todas as noites. At\u00e9 hoje.<b> &nbsp; Majestade<\/b>  <\/p>\n<p>Voc\u00ea sabia? R\u00e9gia, que aparece em vit\u00f3ria-r\u00e9gia,  vem de fam\u00edlia pra l\u00e1 de importante. \u00c9 filhote de rei. Por isso tem realeza.  <b> &nbsp; Ca\u00e7a-palavra<\/b>  <\/p>\n<p>Encontre adjetivo que quer dizer r\u00e9gia:  <\/p>\n<p>BONITASAPECA ARTEIRAREALM ALTIVASOFISTIC PEDIGREEFEIAS<b> &nbsp; A flor  <\/b>  <\/p>\n<p>Vit\u00f3ria-r\u00e9gia \u00e9 uma flor. O nome dela tem duas palavras. Uma  \u00e9 o substantivo <i>vit\u00f3ria<\/i>. A outra, o adjetivo <i>r\u00e9gia<\/i>. No plural, as  duas ganham s. \u00c9 \u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026<b> &nbsp; Resposta<\/b> REAL vit\u00f3rias-r\u00e9gias<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vit\u00f3ria-r\u00e9gia, uma hist\u00f3ria de amor Quando o mundo nasceu, a Lua era guerreiro pra l\u00e1 de valente. Ela iluminava a Terra noite ap\u00f3s noite. Com a claridade, encontrava as \u00edndias bonitas e as transformava em estrelas do c\u00e9u. Nai\u00e1 sonhava ser escolhida. Banhava-se todos os dias sob a luz do luar. Mas a Lua n\u00e3o a via. Ia, ent\u00e3o, para o alto da montanha pra [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62,1],"tags":[],"class_list":["post-428","post","type-post","status-publish","format-standard","hentry","category-diquinhas","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=428"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/428\/revisions"}],"predecessor-version":[{"id":1022,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/428\/revisions\/1022"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}