{"id":4271,"date":"2009-07-30T14:05:00","date_gmt":"2009-07-30T17:05:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitores_encucados\/"},"modified":"2015-11-13T10:40:07","modified_gmt":"2015-11-13T12:40:07","slug":"leitores_encucados","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitores_encucados\/","title":{"rendered":"Leitores encucados"},"content":{"rendered":"\n<p>&nbsp;&nbsp; &nbsp; <\/p>\n<p>M\u00edriam Moura escreve: &#8220;Ora vejo escrito \u201cfeito \u00e0 m\u00e3o\u201d. Ora, \u201cfeito a m\u00e3o\u201d. E da\u00ed? Fico na maior d\u00favida. A crase existe ou n\u00e3o?&#8221; <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">Nem sempre o grampinho resulta de crase (a+a). \u00c0s vezes, por quest\u00e3o de clareza, apela-se para a falsa crase. Usa-se \u00e0 mesmo sem a contra\u00e7\u00e3o da preposi\u00e7\u00e3o com o artigo. \u00c9 o caso de \u201cvender \u00e0 vista\u201d. A\u00ed, n\u00e3o h\u00e1 crase. No masculino, fica claro (vender a prazo). Por que o \u00e0?  <\/p>\n<p>Sem o acento, poder-se-ia entender que se quer vender a vista (o olho). O duplo sentido ocorre nas locu\u00e7\u00f5es que indicam meio e instrumento. Embora n\u00e3o seja obrigat\u00f3rio, usa-se \u00e0 para evitar confus\u00e3o: Matou-o \u00e0 bala. Feriram-se \u00e0 bala. Escrever \u00e0 tinta. Feito \u00e0 m\u00e3o. Fechar \u00e0 chave. Enxotar \u00e0 pedrada.  <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>*** <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Cl\u00e1udio Fontana pergunta: &#8220;Sou concurseiro. Outro dia, uma quest\u00e3o me deixou indeciso. Como uma resposta errada anulava uma certa, achei melhor deixar a pergunta de lado. Tratava-se do verbo intervir. Ele interviu ou interveio? <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>&nbsp;Os verbos t\u00eam pai e m\u00e3e. Intervir \u00e9 filhote de vir. Pai e filho se conjugam do mesmo jeitinho: eu vim (intervim), ele veio (interveio), n\u00f3s viemos (interviemos), eles vieram (intervieram).  <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;&nbsp; &nbsp; M\u00edriam Moura escreve: &#8220;Ora vejo escrito \u201cfeito \u00e0 m\u00e3o\u201d. Ora, \u201cfeito a m\u00e3o\u201d. E da\u00ed? Fico na maior d\u00favida. A crase existe ou n\u00e3o?&#8221; Nem sempre o grampinho resulta de crase (a+a). \u00c0s vezes, por quest\u00e3o de clareza, apela-se para a falsa crase. Usa-se \u00e0 mesmo sem a contra\u00e7\u00e3o da preposi\u00e7\u00e3o com o artigo. \u00c9 o caso de \u201cvender \u00e0 vista\u201d. A\u00ed, n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-4271","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4271"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4271\/revisions"}],"predecessor-version":[{"id":11486,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4271\/revisions\/11486"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}