{"id":4067,"date":"2009-07-14T15:00:00","date_gmt":"2009-07-14T18:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e_pleonasmo-3\/"},"modified":"2009-07-14T15:00:00","modified_gmt":"2009-07-14T18:00:00","slug":"e_pleonasmo-3","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e_pleonasmo-3\/","title":{"rendered":"\u00c9 pleonasmo"},"content":{"rendered":"\n<p>Pequenos detalhes? \u00c9 pleonasmo. Joga no time do subir pra cima, descer pra baixo, entrar pra dentro ou sair pra fora. Toda subida \u00e9 pra cima, toda descida \u00e9 pra baixo, toda entrada \u00e9 pra dentro, toda sa\u00edda \u00e9 pra fora. E, claro, todo detalhe \u00e9 pequeno. Basta detalhe.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pequenos detalhes? \u00c9 pleonasmo. Joga no time do subir pra cima, descer pra baixo, entrar pra dentro ou sair pra fora. Toda subida \u00e9 pra cima, toda descida \u00e9 pra baixo, toda entrada \u00e9 pra dentro, toda sa\u00edda \u00e9 pra fora. E, claro, todo detalhe \u00e9 pequeno. Basta detalhe.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4067","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=4067"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/4067\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=4067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=4067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=4067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}