{"id":3890,"date":"2009-05-01T06:00:00","date_gmt":"2009-05-01T09:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/alerta\/"},"modified":"2009-05-01T06:00:00","modified_gmt":"2009-05-01T09:00:00","slug":"alerta","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/alerta\/","title":{"rendered":"Alerta"},"content":{"rendered":"<p><strong> <\/p>\n<p><\/strong>  <\/p>\n<p>A gripe su\u00edna assusta gregos e troianos.  Muitos correm \u00e0s farm\u00e1cias. Compram rem\u00e9dios para prevenir o mal. A Organiza\u00e7\u00e3o  Mundial da Sa\u00fade ficou preocupada. Chamou a aten\u00e7\u00e3o para o risco de duas  palavras pra l\u00e1 de conhecidas \u2014 automedica\u00e7\u00e3o e antigripal. Ningu\u00e9m deve  prescrever medicamentos para si mesmo. No caso, as drogas que combatem n\u00e3o  previnem a gripe.   <\/p>\n<p>Os dois voc\u00e1bulos remetem para a reforma  ortogr\u00e1fica. Mais especificamente:&nbsp;ao  emprego do h\u00edfen. No mont\u00e3o de regras, uma vale ouro. Letras iguais, diz ela, se  rejeitam. Letras diferentes se atraem. Por isso automedica\u00e7\u00e3o se  escreve sem tracinho (o <strong>o<\/strong> de aut<strong>o<\/strong> morre de  paix\u00e3o pelo <strong>m <\/strong>de <strong>m<\/strong>edica\u00e7\u00e3o). Mas  aut<strong>o<\/strong>&#8211;<strong>o<\/strong>rienta\u00e7\u00e3o se grafam com elo (o  <strong>o<\/strong> de aut<strong>o<\/strong> tem alergia ao <strong>o<\/strong> de  <strong>o<\/strong>rienta\u00e7\u00e3o). O mesmo ocorre com antigripal e  anti-imperialismo.<b> &nbsp;<\/b> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A gripe su\u00edna assusta gregos e troianos. Muitos correm \u00e0s farm\u00e1cias. Compram rem\u00e9dios para prevenir o mal. A Organiza\u00e7\u00e3o Mundial da Sa\u00fade ficou preocupada. Chamou a aten\u00e7\u00e3o para o risco de duas palavras pra l\u00e1 de conhecidas \u2014 automedica\u00e7\u00e3o e antigripal. Ningu\u00e9m deve prescrever medicamentos para si mesmo. No caso, as drogas que combatem n\u00e3o previnem a gripe. Os dois voc\u00e1bulos remetem para a reforma [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3890","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=3890"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3890\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=3890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=3890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=3890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}