{"id":386,"date":"2015-05-18T10:00:00","date_gmt":"2015-05-18T10:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/05\/18\/licao_machadiana\/"},"modified":"2015-10-23T16:57:04","modified_gmt":"2015-10-23T18:57:04","slug":"licao_machadiana","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/licao_machadiana\/","title":{"rendered":"Li\u00e7\u00e3o machadiana"},"content":{"rendered":"<p><b> <\/b> &#8220;As  frases feitas s\u00e3o a companhia cooperativa do esp\u00edrito. D\u00e3o o trabalho   \u00fanico de as meter na cabe\u00e7a, guard\u00e1-las e aplic\u00e1-las oportunamente, sem  dispensa  de convic\u00e7\u00e3o, \u00e9 claro, nem daquele fino sentimento de  originalidade que faz um  molambo seda.&#8221; (Machado de Assis)<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;As frases feitas s\u00e3o a companhia cooperativa do esp\u00edrito. D\u00e3o o trabalho \u00fanico de as meter na cabe\u00e7a, guard\u00e1-las e aplic\u00e1-las oportunamente, sem dispensa de convic\u00e7\u00e3o, \u00e9 claro, nem daquele fino sentimento de originalidade que faz um molambo seda.&#8221; (Machado de Assis)<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-386","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=386"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/386\/revisions"}],"predecessor-version":[{"id":1066,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/386\/revisions\/1066"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}