{"id":3797,"date":"2009-04-20T08:00:00","date_gmt":"2009-04-20T11:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/ferias-2\/"},"modified":"2009-04-20T08:00:00","modified_gmt":"2009-04-20T11:00:00","slug":"ferias-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/ferias-2\/","title":{"rendered":"F\u00e9rias"},"content":{"rendered":"<p>&nbsp; &nbsp; Amigos, estou de f\u00e9rias. Por isso o blog n\u00e3o tem tido atualiza\u00e7\u00e3o em tempo real. Mas todos os dias h\u00e1, pelo menos, uma novidade. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Amigos, estou de f\u00e9rias. Por isso o blog n\u00e3o tem tido atualiza\u00e7\u00e3o em tempo real. Mas todos os dias h\u00e1, pelo menos, uma novidade.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3797","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=3797"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3797\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=3797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=3797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=3797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}