{"id":371,"date":"2015-05-10T00:05:00","date_gmt":"2015-05-10T00:05:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/05\/10\/matriz_da_humanidade\/"},"modified":"2015-10-23T16:57:08","modified_gmt":"2015-10-23T18:57:08","slug":"matriz_da_humanidade","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/matriz_da_humanidade\/","title":{"rendered":"Matriz da humanidade"},"content":{"rendered":"<p>Homenagear a m\u00e3e \u00e9 tradi\u00e7\u00e3o mais antiga que o rascunho da <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">B\u00edblia<\/i>. Na  Gr\u00e9cia antiga, na Roma dos C\u00e9sares, na Idade M\u00e9dia, o povo reverenciava a mulher  que d\u00e1 \u00e0 luz meninos e meninas. Ela n\u00e3o era convocada para lutar nos campos de  batalha. A raz\u00e3o: ser a matriz da humanidade \u2013 capaz de equilibrar a popula\u00e7\u00e3o  depois dos estragos causados pela guerra.<\/p>\n<div>\n<div>\n<p>H\u00e1 um s\u00e9culo, os Estados Unidos institu\u00edram o Dia das M\u00e3es. O presidente  Woodrow Wilson oficializou 9 de maio para a festa. O Brasil importou a ideia 82  anos depois. Get\u00falio Vargas introduziu a data \u2013 segundo domingo de maio \u2014 no  calend\u00e1rio verde-amarelo em 1932. De l\u00e1 pra c\u00e1, \u00e9 s\u00f3 festa. M\u00e3es, shoppings e  restaurantes batem palmas. Viva!<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p>Como foi?<\/b>  <\/p>\n<p>Annie Jerwis perdeu a m\u00e3e. Ficou t\u00e3o triste que caiu em profunda depress\u00e3o.  Preocupadas com o sofrimento da jovem, amigas queriam consol\u00e1-la. Como?  Promoveram senhora festa em mem\u00f3ria da falecida. Repetiram-na no ano seguinte. E  no seguinte. E no seguinte. Annie quis estender a homenagem a todas as m\u00e3ezonas,  vivas e mortas. A ideia pegou. Faz sucesso at\u00e9 hoje.<b><\/b><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Homenagear a m\u00e3e \u00e9 tradi\u00e7\u00e3o mais antiga que o rascunho da B\u00edblia. Na Gr\u00e9cia antiga, na Roma dos C\u00e9sares, na Idade M\u00e9dia, o povo reverenciava a mulher que d\u00e1 \u00e0 luz meninos e meninas. Ela n\u00e3o era convocada para lutar nos campos de batalha. A raz\u00e3o: ser a matriz da humanidade \u2013 capaz de equilibrar a popula\u00e7\u00e3o depois dos estragos causados pela guerra. H\u00e1 um [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-371","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=371"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/371\/revisions"}],"predecessor-version":[{"id":1077,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/371\/revisions\/1077"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}