{"id":361,"date":"2015-05-06T13:00:00","date_gmt":"2015-05-06T13:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/05\/06\/realeza_inglesa\/"},"modified":"2015-10-23T16:57:13","modified_gmt":"2015-10-23T18:57:13","slug":"realeza_inglesa","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/realeza_inglesa\/","title":{"rendered":"Realeza inglesa"},"content":{"rendered":"<p><b> <\/b> Realeza se grafa com z. Inglesa, com s. Por qu\u00ea? A resposta  n\u00e3o est\u00e1 na pron\u00fancia. Nos dois voc\u00e1bulos, o som \u00e9 o mesmo. A diferen\u00e7a tem a  ver com a origem da palavra:  <\/p>\n<p>1. Os sufixos -eza e -ez formam substantivos abstratos  derivados de adjetivo: <i>limpo (limpeza) grande (grandeza), rico (riqueza),  safado (safadeza), sutil (sutileza),<\/i> <i>macio (maciez), honrado (honradez),  altivo (altivez), l\u00facido (lucidez), mudo (mudez), sensato (sensatez), surdo  (surdez).<\/i>  <\/p>\n<p>2. Os sufixos -es e -esa formam adjetivos derivados de  substantivo: <i>Inglaterra (ingl\u00eas, inglesa), Portugal (portugu\u00eas, portuguesa),  Esc\u00f3cia (escoc\u00eas, escocesa), Fran\u00e7a (franc\u00eas, francesa), freguesia (fregu\u00eas,  freguesa), burgo (burgu\u00eas, burguesa)<\/i>.<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p>Superdica<\/b>  <\/p>\n<p>Na d\u00favida, seja esperto. Respire fundo, pare e pense. A  palavra deriva de substantivo? D\u00ea passagem ao s. De adjetivo? D\u00ea a vez ao z. A  origem \u00e9 a chave do enigma.<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realeza se grafa com z. Inglesa, com s. Por qu\u00ea? A resposta n\u00e3o est\u00e1 na pron\u00fancia. Nos dois voc\u00e1bulos, o som \u00e9 o mesmo. A diferen\u00e7a tem a ver com a origem da palavra: 1. Os sufixos -eza e -ez formam substantivos abstratos derivados de adjetivo: limpo (limpeza) grande (grandeza), rico (riqueza), safado (safadeza), sutil (sutileza), macio (maciez), honrado (honradez), altivo (altivez), l\u00facido (lucidez), mudo [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-361","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=361"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/361\/revisions"}],"predecessor-version":[{"id":1088,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/361\/revisions\/1088"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}