{"id":3428,"date":"2009-06-03T06:00:00","date_gmt":"2009-06-03T09:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/diz_sem_dizer\/"},"modified":"2009-06-03T06:00:00","modified_gmt":"2009-06-03T09:00:00","slug":"diz_sem_dizer","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/diz_sem_dizer\/","title":{"rendered":"Diz sem dizer"},"content":{"rendered":"<p><b>  <\/p>\n<p><\/b>  <\/p>\n<p>&#8220;A tripula\u00e7\u00e3o de avi\u00e3o da TAM teria visto pontos luminosos no espa\u00e7o a\u00e9reo do  Senegal&#8221;, disse Jos\u00e9 Alencar. O vice-presidente foi ao Rio consolar as fam\u00edlias  dos passageiros da Air France. Reparou no tempo verbal? Ele disse &#8220;teria visto&#8221;.  Por qu\u00ea? \u00c9 forma de n\u00e3o afirmar. Se tivesse dito &#8220;viu&#8221;, estaria se comprometendo  com a informa\u00e7\u00e3o. O &#8220;teria visto&#8221; abre espa\u00e7o para o sim e o n\u00e3o.  <b><\/b> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;A tripula\u00e7\u00e3o de avi\u00e3o da TAM teria visto pontos luminosos no espa\u00e7o a\u00e9reo do Senegal&#8221;, disse Jos\u00e9 Alencar. O vice-presidente foi ao Rio consolar as fam\u00edlias dos passageiros da Air France. Reparou no tempo verbal? Ele disse &#8220;teria visto&#8221;. Por qu\u00ea? \u00c9 forma de n\u00e3o afirmar. Se tivesse dito &#8220;viu&#8221;, estaria se comprometendo com a informa\u00e7\u00e3o. O &#8220;teria visto&#8221; abre espa\u00e7o para o sim e [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3428","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=3428"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3428\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=3428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=3428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=3428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}