{"id":331,"date":"2015-04-23T16:00:00","date_gmt":"2015-04-23T16:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/04\/23\/erramos-64\/"},"modified":"2015-11-12T12:12:01","modified_gmt":"2015-11-12T14:12:01","slug":"erramos-64","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-64\/","title":{"rendered":"Erramos"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> &#8220;O PMDB, de Temer, articulou o robusto reajuste do Fundo Partid\u00e1rio, que n\u00e3o  sofrer\u00e1 vetos de Dilma&#8221;, escrevemos na&nbsp;legenda da  p\u00e1g. 3. Erramos o tempo, n\u00e3o? Dilma  j\u00e1 sancionou o aumento. Em vez de futuro, o pret\u00e9rito pede passagem: O PMDB,  de Temer, articulou o robusto reajuste do Fundo Partid\u00e1rio, que n\u00e3o sofreu vetos  de Dilma.<\/div>\n<div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O PMDB, de Temer, articulou o robusto reajuste do Fundo Partid\u00e1rio, que n\u00e3o sofrer\u00e1 vetos de Dilma&#8221;, escrevemos na&nbsp;legenda da p\u00e1g. 3. Erramos o tempo, n\u00e3o? Dilma j\u00e1 sancionou o aumento. Em vez de futuro, o pret\u00e9rito pede passagem: O PMDB, de Temer, articulou o robusto reajuste do Fundo Partid\u00e1rio, que n\u00e3o sofreu vetos de Dilma.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-331","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=331"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/331\/revisions"}],"predecessor-version":[{"id":1119,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/331\/revisions\/1119"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}