{"id":316,"date":"2015-04-19T00:00:00","date_gmt":"2015-04-19T00:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/04\/19\/e_guerra\/"},"modified":"2015-10-23T16:58:27","modified_gmt":"2015-10-23T18:58:27","slug":"e_guerra","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e_guerra\/","title":{"rendered":"\u00c9 guerra"},"content":{"rendered":"<p><b> <\/b> A palavra da moda? \u00c9 terceirizar. Ela est\u00e1 na boca de patr\u00f5es e  empregados. Uns a veem como inimiga das conquistas trabalhistas desde que o  Brasil \u00e9 Brasil. Outros a consideram a salva\u00e7\u00e3o da p\u00e1tria. Moderniza a  legisla\u00e7\u00e3o, amplia o n\u00famero de empregos e torna competitivos os produtos  verde-amarelos.   <\/p>\n<p>Enquanto a discuss\u00e3o corre solta e os protestos paralisam o  pa\u00eds, vale a quest\u00e3o. Por que terceirizar se escreve com z? A resposta \u00e9 pra l\u00e1  de simples. N\u00e3o existe o sufixo -isar. S\u00f3 existe -izar. Ops! Voc\u00ea pode se  lembrar de mont\u00f5es de palavras terminadas em -isar. \u00c9 o caso de frisar,  pesquisar, analisar, encamisar. E da\u00ed?<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p>Sagrada fam\u00edlia<\/b><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/b>  <\/p>\n<p>Na l\u00edngua, uma regra vem \u00e0 frente de todas. Trata-se do respeito  \u00e0 fam\u00edlia. &#8220;Tal pai, tal filho&#8221;, diz ela. Em bom portugu\u00eas: se a palavra  primitiva se escreve com determinada letra, as derivadas a mant\u00eam: <i>luxo  (luxento, luxuoso, lux\u00faria, luxuriante), cheio (encher, enchente), casa  (casinha, casebre, casona, casar\u00e3o), luz (luzente, luzeiro, reluzente, luzir),  pesquisa (pesquisar, pesquisador, pesquisado), an\u00e1lise (analisar, analisado),  friso (frisar, frisado, frisador, frisante).<\/i>  <\/p>\n<p>Meio \u00f3rf\u00e3o <\/p>\n<p>H\u00e1 palavras que n\u00e3o t\u00eam <b>s<\/b> no radical. Pra formar verbos  terminados em -izar, s\u00f3 h\u00e1 um jeito. Recorrer ao sufixo escrito com <b>z<\/b>. \u00c9  o caso de <i>terceiro (terceirizar), civil (civilizar), normal (normalizar),  canal (canalizar), global (globalizar), polo (polarizar), fiscal (fiscalizar),  m\u00ednimo (minimizar), m\u00e1ximo (maximizar).<\/i>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A palavra da moda? \u00c9 terceirizar. Ela est\u00e1 na boca de patr\u00f5es e empregados. Uns a veem como inimiga das conquistas trabalhistas desde que o Brasil \u00e9 Brasil. Outros a consideram a salva\u00e7\u00e3o da p\u00e1tria. Moderniza a legisla\u00e7\u00e3o, amplia o n\u00famero de empregos e torna competitivos os produtos verde-amarelos. Enquanto a discuss\u00e3o corre solta e os protestos paralisam o pa\u00eds, vale a quest\u00e3o. Por que [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-316","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=316"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/316\/revisions"}],"predecessor-version":[{"id":1115,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/316\/revisions\/1115"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}