{"id":312,"date":"2015-04-16T17:00:00","date_gmt":"2015-04-16T17:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/04\/16\/erramos-59\/"},"modified":"2015-11-12T12:13:07","modified_gmt":"2015-11-12T14:13:07","slug":"erramos-59","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-59\/","title":{"rendered":"Erramos"},"content":{"rendered":"<p>&#8220;No entanto, ela foi ouvida por delegados na sua pr\u00f3pria resid\u00eancia&#8221;,  escrevemos na p\u00e1g. 3. Sua pr\u00f3pria? \u00c9 redund\u00e2ncia. Melhor evitar desperd\u00edcios:  <i>No entanto, ela foi ouvida por delegados na pr\u00f3pria resid\u00eancia.<\/i>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;No entanto, ela foi ouvida por delegados na sua pr\u00f3pria resid\u00eancia&#8221;, escrevemos na p\u00e1g. 3. Sua pr\u00f3pria? \u00c9 redund\u00e2ncia. Melhor evitar desperd\u00edcios: No entanto, ela foi ouvida por delegados na pr\u00f3pria resid\u00eancia.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-312","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=312"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/312\/revisions"}],"predecessor-version":[{"id":1127,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/312\/revisions\/1127"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}