{"id":3103,"date":"2009-01-03T00:00:00","date_gmt":"2009-01-03T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_sabia_e_o_urubu_-_a_inveja\/"},"modified":"2009-01-03T00:00:00","modified_gmt":"2009-01-03T02:00:00","slug":"o_sabia_e_o_urubu_-_a_inveja","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_sabia_e_o_urubu_-_a_inveja\/","title":{"rendered":"O sabi\u00e1 e o urubu &#8212; a inveja"},"content":{"rendered":"<p><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Era uma vez\u2026<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Um sabi\u00e1 cantava como s\u00f3 ele sabe cantar. A bicharada da floresta parava para ouvir. Estavam todos encantados com o gorjeio do p\u00e1ssaro. No fim, batiam muiiiiiiiiiiiiiiiiiiiiiiiiiiiitas palmas.&nbsp; S\u00f3 um n\u00e3o se conformava com tanta beleza. Era o urubu. Sabe por qu\u00ea? Ele morria de inveja. Homens e animais adoram o sabi\u00e1. Querem ficar pertinho dele. Mas morrem de medo do urubu. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>O invejoso resolveu acabar com a alegria do outro. Quando os bichos foram pra casa, pediu ao sabi\u00e1 que cantasse de novo. O sabi\u00e1 ficou com medo, mas atendeu o pedido. O urubu foi chegando perto, chegando perto e\u2026quase pegou o cantor. Mas o sabi\u00e1 conseguiu fugiu. Antes de voar, perguntou:<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>\u2014 Que mal eu lhe fiz? Por que voc\u00ea queria me matar?<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>\u2014 Eu nunca vou cantar como voc\u00ea. Ter talento \u00e9 seu grande crime.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>*<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Sabia? Na vida da gente tamb\u00e9m h\u00e1 invejosos. Outro dia, Jo\u00e3o, Rafael, Malu, Vinicius, Cau\u00e3, Mateus e outros amiguinhos estavam pintando. Havia muitos pinc\u00e9is e muitas tintas. Era uma alegria s\u00f3. Todos faziam trabalhos lindos. Um garoto que n\u00e3o quis entrar na brincadeira resolveu acabar com a festa. Derramou todas as tintas. Que coisa! Entra na brincadeira, menino!&nbsp;&nbsp;&nbsp; &nbsp;<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>*<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Moral da hist\u00f3ria: Inveja mata. O invejoso n\u00e3o aguenta o talento dos outros. <\/p>\n<p>(Coluna publicada no suplemento infantil Super, que circula aos s\u00e1bados no Correio Braziliense)<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era uma vez\u2026 Um sabi\u00e1 cantava como s\u00f3 ele sabe cantar. A bicharada da floresta parava para ouvir. Estavam todos encantados com o gorjeio do p\u00e1ssaro. No fim, batiam muiiiiiiiiiiiiiiiiiiiiiiiiiiiitas palmas.&nbsp; S\u00f3 um n\u00e3o se conformava com tanta beleza. Era o urubu. Sabe por qu\u00ea? Ele morria de inveja. Homens e animais adoram o sabi\u00e1. Querem ficar pertinho dele. Mas morrem de medo do urubu. [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3103","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=3103"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3103\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=3103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=3103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=3103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}