{"id":308,"date":"2015-04-15T12:00:00","date_gmt":"2015-04-15T12:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/04\/15\/lingua_portuguesa_no_ceu\/"},"modified":"2015-10-23T16:58:32","modified_gmt":"2015-10-23T18:58:32","slug":"lingua_portuguesa_no_ceu","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/lingua_portuguesa_no_ceu\/","title":{"rendered":"L\u00edngua portuguesa no c\u00e9u"},"content":{"rendered":"<p><b> <\/b> Santo de casa faz milagre? H\u00e1 quem diga que n\u00e3o. Mas \u00e9  confort\u00e1vel saber que l\u00e1 no c\u00e9u algu\u00e9m entende a nossa l\u00edngua. Assim, talvez num  momento de folga, ele tenha um tempinho pra nos escutar. O mais novo candidato a  vaga na casa do Senhor \u00e9 Dom H\u00e9lder C\u00e2mara. Oba!  <\/p>\n<p>A not\u00edcia recebeu aplausos de norte a sul do pa\u00eds. Jornais,  r\u00e1dios e tev\u00eas divulgaram a novidade. As m\u00eddias sociais comentaram com  entusiasmo a indica\u00e7\u00e3o. No arrebatamento, n\u00e3o deu outra. Trombaram na l\u00edngua.  &#8220;D. H\u00e9lder foi testemunho vivo da vontade de Deus&#8221;, escreveram baianos, goianos,  romanos e demais g\u00eaneros humanos.  <\/p>\n<p>Bobearam. Testemunho e testemunha jogam em times parecidos  mas desiguais. N\u00e3o se trata de diferen\u00e7a de sexo como menino e menina, garoto e  garota, mo\u00e7o e mo\u00e7a. O masculino e o feminino mudam o significado das palavras.  Testemunha \u00e9 a pessoa. Testemunho, o depoimento: <i>A testemunha deu seu  testemunho na pol\u00edcia. D. H\u00e9lder foi testemunha viva da vontade de  Deus.<\/i><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> &nbsp;<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo de casa faz milagre? H\u00e1 quem diga que n\u00e3o. Mas \u00e9 confort\u00e1vel saber que l\u00e1 no c\u00e9u algu\u00e9m entende a nossa l\u00edngua. Assim, talvez num momento de folga, ele tenha um tempinho pra nos escutar. O mais novo candidato a vaga na casa do Senhor \u00e9 Dom H\u00e9lder C\u00e2mara. Oba! A not\u00edcia recebeu aplausos de norte a sul do pa\u00eds. Jornais, r\u00e1dios e tev\u00eas [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-308","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=308"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/308\/revisions"}],"predecessor-version":[{"id":1134,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/308\/revisions\/1134"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}