{"id":3027,"date":"2008-12-10T00:00:00","date_gmt":"2008-12-10T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/copa_de_2014\/"},"modified":"2008-12-10T00:00:00","modified_gmt":"2008-12-10T02:00:00","slug":"copa_de_2014","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/copa_de_2014\/","title":{"rendered":"Copa de 2014"},"content":{"rendered":"<p>  <BR>&nbsp; &#8220;As conseq\u00fc\u00eancias&#8221;, diz o conselheiro Ac\u00e1cio, &#8220;v\u00eam depois.&#8221; Por isso os brasilienses est\u00e3o tremendo nas bases. Eles querem porque querem aplaudir em casa jogos da Copa do Mundo de 2014. O Bezerr\u00e3o ganhou cara nova para receber times de Europa, Fran\u00e7a e Bahia. E agora? Eles temem esquecer a conjuga\u00e7\u00e3o do verbo sediar. Pra manter a mem\u00f3ria viva, vale lembrar. Sediar e maquiar se flexionam do mesmo jeitinho: eu sedio (maquio), ele sedia (maquia), n\u00f3s sediamos (maquiamos), eles sediam (maquiam); eu sediei (maquiei), ele sediou (maquiou), n\u00f3s sediamos (maquiamos), eles sediaram (maquiaram). E por a\u00ed vai.&nbsp; <BR>&nbsp; <BR><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &#8220;As conseq\u00fc\u00eancias&#8221;, diz o conselheiro Ac\u00e1cio, &#8220;v\u00eam depois.&#8221; Por isso os brasilienses est\u00e3o tremendo nas bases. Eles querem porque querem aplaudir em casa jogos da Copa do Mundo de 2014. O Bezerr\u00e3o ganhou cara nova para receber times de Europa, Fran\u00e7a e Bahia. E agora? Eles temem esquecer a conjuga\u00e7\u00e3o do verbo sediar. Pra manter a mem\u00f3ria viva, vale lembrar. Sediar e maquiar se [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3027","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=3027"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3027\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=3027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=3027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=3027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}