{"id":3017,"date":"2008-12-08T08:12:00","date_gmt":"2008-12-08T10:12:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_redacao_do_vestibular\/"},"modified":"2008-12-08T08:12:00","modified_gmt":"2008-12-08T10:12:00","slug":"a_redacao_do_vestibular","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_redacao_do_vestibular\/","title":{"rendered":"A reda\u00e7\u00e3o do vestibular"},"content":{"rendered":"<p><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">Os 10 mandamentos do estilo (1)<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">No vestibular, voc\u00ea vai escrever uma reda\u00e7\u00e3o de 30 linhas. Como chegar l\u00e1? H\u00e1 duas semanas, a coluna deu dicas de planejamento do texto. Hoje, vamos adiante. Nosso tema ser\u00e1 o estilo \u2014 o recheio do planejamento. Montaigne, h\u00e1 400 anos, apontou o norte. \u201cO estilo\u201d, disse ele, \u201cdeve ter tr\u00eas virtudes: clareza, clareza eclareza.&#8221;  <\/p>\n<p>Certo. N\u00f3s escrevemos para o leitor. Queremos que ele leia e entenda nossa reda\u00e7\u00e3o. Mais: que aprecie a leitura, Com os dados \u00e0 m\u00e3o, objetivo definido e plano tra\u00e7ado, \u00e9 hora de redigir. Como? Sem perder de vista o leitor. Seja natural. Imagine que ele esteja \u00e0 sua frente ou ao telefone conversando com voc\u00ea. Fique \u00e0 vontade. Espaceje suas frases com pausas e, sempre que couber, com perguntas diretas. Confira ao texto um toque humano. Voc\u00ea est\u00e1 escrevendo para as pessoas. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>N\u00e3o o canse. V\u00e1 direto ao assunto. Comece pelo mais importante. E comece bem, com uma frase atraente, que lhe desperte o interesse e o estimule a prosseguir a leitura. No final, d\u00ea-lhe o pr\u00eamio: um fecho de ouro, como inesquec\u00edvel sobremesa a coroar um almo\u00e7o de pr\u00edncipes. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Os dados, o objetivo e o plano s\u00e3o os ingredientes. A forma de prepar\u00e1-los \u00e9 que d\u00e1 o toque especial ao prato. Uma frase particularmente elegante, capaz de veicular com clareza e simplicidade a mensagem que voc\u00ea quer transmitir, \u00e9 conquista pessoal, exerc\u00edcio di\u00e1rio de desapego, humildade e vontade de melhorar. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>William Strunk Jr, professor de altos estudos da l\u00edngua inglesa, costumava dizer: \u201cA prosa vigorosa \u00e9 concisa. A frase n\u00e3o deve ter palavras desnecess\u00e1rias, nem o par\u00e1grafo frases desnecess\u00e1rias, pela mesma raz\u00e3o que o desenho n\u00e3o deve ter linhas desnecess\u00e1rias, nem a m\u00e1quina partes desnecess\u00e1rias. Isso n\u00e3o quer dizer que o autor fa\u00e7a breves todas as frases, nem que evite todo detalhe, nem que trate os temas s\u00f3 na superf\u00edcie: apenas que cada palavra conta\u201c. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Frase curta <\/p>\n<p>Os segredos do estilo mais eficiente podem ser resumidos em 10 preceitos. Vamos ao primeiro. Nas pr\u00f3ximas colunas, vir\u00e3o os demais.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>1. Use frases curtas e incisivas. O leitor s\u00f3 consegue dominar determinado n\u00famero de palavras antes que seus olhos pe\u00e7am uma pausa. Se a frase for muito longa, ele se sentir\u00e1 perdido, sem capacidade de compreender-lhe o completo significado. Por isso, use senten\u00e7as de, no m\u00e1ximo, duas linhas. Lembre-se de que uma frase longa nada mais \u00e9 do que duas curtas.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>H\u00e1 formas e formas de encurtar a compridona. Em todas, a vedete \u00e9 o ponto. O sinalzinho d\u00e1 uma pausa ao leitor. Permite que ele respire e capte o que foi dito. Em suma: prepara-o para prosseguir. Onde usar o redondinho?<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>1. Transforme ora\u00e7\u00f5es coordenadas em outro per\u00edodo:<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>H\u00e1 quem leve a vida inteira a ler sem ter nunca conseguido ir al\u00e9m da leitura, ficam apegados \u00e0 p\u00e1gina, n\u00e3o percebem que as palavras s\u00e3o apenas pedras postas a atravessar a corrente de um rio, se est\u00e3o ali \u00e9 para que possamos chegar \u00e0 outra margem, a outra margem \u00e9 o que importa.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Vamos aos pontos? <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>H\u00e1 quem leve a vida inteira a ler sem ter nunca conseguido ir al\u00e9m da leitura. Ficam apegados \u00e0 p\u00e1gina. N\u00e3o percebem que as palavras s\u00e3o apenas pedras postas a atravessar a corrente de um rio. Se est\u00e3o ali \u00e9 para que possamos chegar \u00e0 outra margem. A outra margem \u00e9 o que importa. <\/p>\n<p><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">2. Substitua o ger\u00fandio por ponto:<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Alunos rec\u00e9m-aprovados no vestibular bater\u00e3o \u00e0s portas da universidade cheios de entusiasmo no in\u00edcio da nova jornada, podendo, por\u00e9m, se decepcionar se n\u00e3o forem satisfeitas as esperan\u00e7as que nutrem.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Venha, pausa:<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Alunos rec\u00e9m-aprovados no vestibular bater\u00e3o \u00e0s portas da universidade cheios de entusiasmo no in\u00edcio da nova jornada. Poder\u00e3o, por\u00e9m, se decepcionar se n\u00e3o forem satisfeitas as esperan\u00e7as que nutrem. <\/p>\n<p>(Coluna publicada no suplemento Gabarito, que circula \u00e0s segundas no Correio Brasiliense)<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os 10 mandamentos do estilo (1)No vestibular, voc\u00ea vai escrever uma reda\u00e7\u00e3o de 30 linhas. Como chegar l\u00e1? H\u00e1 duas semanas, a coluna deu dicas de planejamento do texto. Hoje, vamos adiante. Nosso tema ser\u00e1 o estilo \u2014 o recheio do planejamento. Montaigne, h\u00e1 400 anos, apontou o norte. \u201cO estilo\u201d, disse ele, \u201cdeve ter tr\u00eas virtudes: clareza, clareza eclareza.&#8221; Certo. N\u00f3s escrevemos para o [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3017","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=3017"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3017\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=3017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=3017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=3017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}