{"id":3006,"date":"2008-12-05T00:00:00","date_gmt":"2008-12-05T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/os_10_mandamentos_do_estilo\/"},"modified":"2008-12-05T00:00:00","modified_gmt":"2008-12-05T02:00:00","slug":"os_10_mandamentos_do_estilo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/os_10_mandamentos_do_estilo\/","title":{"rendered":"Os 10 mandamentos do estilo"},"content":{"rendered":"\n<p>&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;  <\/p>\n<p><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;\u201cO estilo deve ter tr\u00eas virtudes: clareza, clareza eclareza.&#8221;<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;Anatole France<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>&nbsp;&nbsp;&nbsp; N\u00f3s escrevemos para o leitor. Queremos que ele leia e entenda&nbsp; nosso texto.&nbsp; E&nbsp; mais: que aprecie a leitura, que n\u00e3o se arrependa da escolha. Os cinco, dez ou vinte minutos investidos no artigo, reportagem ou entrevista devem ter retorno garantido: apura\u00e7\u00e3o s\u00e9ria, informa\u00e7\u00f5es corretas e estilo atraente.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp; &nbsp;Com os dados \u00e0 m\u00e3o, objetivo definido e plano tra\u00e7ado, \u00e9 hora de redigir. Como? Sem perder de vista o leitor. Seja natural. Imagine que ele esteja \u00e0 sua frente ou ao telefone conversando com voc\u00ea. Fique \u00e0 vontade. Espaceje suas frases com pausas e, sempre que couber, com perguntas diretas. Confira ao texto um toque humano. Voc\u00ea est\u00e1 escrevendo para as pessoas.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp; &nbsp;N\u00e3o o canse. V\u00e1 direto ao assunto. Comece pelo mais importante. E comece bem, com uma frase atraente, que lhe desperte o interesse e o estimule a prosseguir a leitura. No final, d\u00ea-lhe o pr\u00eamio: um fecho de ouro, como inesquec\u00edvel sobremesa&nbsp; a coroar um lauto almo\u00e7o.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp; &nbsp;Os dados, o objetivo e o plano s\u00e3o os ingredientes.&nbsp; A forma de prepar\u00e1-los \u00e9 que d\u00e1 o toque especial ao prato.&nbsp; Uma frase particularmente elegante, capaz de veicular com clareza e simplicidade a mensagem que voc\u00ea quer transmitir, \u00e9 conquista pessoal, exerc\u00edcio di\u00e1rio de desapego, humildade e vontade de melhorar.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp; &nbsp; &nbsp;<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; William Strunk Jr, professor de altos estudos da l\u00edngua inglesa, costumava dizer: \u201cA prosa vigorosa \u00e9 concisa. A frase n\u00e3o deve ter palavras desnecess\u00e1rias, nem o par\u00e1grafo frases desnecess\u00e1rias, pela mesma raz\u00e3o que o desenho n\u00e3o deve ter linhas desnecess\u00e1rias, nem a m\u00e1quna partes desnecess\u00e1rias. Isso n\u00e3o quer dizer que o autor fa\u00e7a breves todas as suas frases, nem que evite todo detalhe, nem que trate seus temas s\u00f3 na superf\u00edcie: apenas que cada palavra conta\u201c.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>&nbsp;&nbsp;&nbsp; Os segredos do estilo mais eficiente podem ser resumidos em dez preceitos:<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>1. Use frases curtas e incisivas<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp;&nbsp; O leitor s\u00f3 consegue dominar determinado n\u00famero de palvras antes que seus olhos pe\u00e7am uma pausa. Se a frase for muito longa, ele se sentir\u00e1 perdido, sem capacidade de compreender-lhe o completo significado. Por isso, use senten\u00e7as de, no m\u00e1ximo, uma linha e meia. Lembre-se de que uma frase longa nada mais \u00e9 do que duas curtas.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp;  <\/p>\n<p>2. Prefira palavras breves e simples<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Palavras longas e pomposas funcionam como uma cortina de fuma\u00e7a entre quem escreve e quem l\u00ea. Seja simples. Entre dois voc\u00e1bulos, prefira o mais curto. Entre dois curtos, o mais expressivo.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>3. Ponha as senten\u00e7as na forma positiva<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; A regra \u00e9 dizer o que \u00e9, n\u00e3o o que n\u00e3o \u00e9. N\u00e3o ser honesto \u00e9 ser desonesto; n\u00e3o lembrar \u00e9 esquecer; n\u00e3o dar aten\u00e7\u00e3o \u00e9 ignorar; n\u00e3o comparecer \u00e9 faltar; n\u00e3o pagar em dia \u00e9 atrasar o pagamento.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;  <\/p>\n<p>&nbsp; Dizer o que n\u00e3o \u00e9 em geral soa hesitante, impreciso, pouco objetivo. D\u00e1 a impress\u00e3o de se estar fugindo do compromisso de afirmar. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>&nbsp;&nbsp;&nbsp; Compare as frases:<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Ele n\u00e3o acredita que o ministro chegue a tempo. Ele duvida que o ministro chegue a tempo).<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">O presidente eleito diz que n\u00e3o far\u00e1 altera\u00e7\u00f5es profundas no Plano Real.&nbsp; O presidente eleito nega que fa\u00e7a altera\u00e7\u00f5es profundas no Plano Real.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">Vargas Llosa n\u00e3o chegar\u00e1 hoje . Vargas Llosa chegar\u00e1 no s\u00e1bado.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; 4. Opte pela voz ativa<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; A voz ativa \u00e9 mais direta, vigorosa e concisa que a passiva. D\u00ea-lhe prefer\u00eancia sempre que puder. Ciro Gomes caracterizou o compuls\u00f3rio como medida transit\u00f3ria \u00e9 constru\u00e7\u00e3o prefer\u00edvel a O compuls\u00f3rio foi caracterizado por Ciro Gomes como medida transit\u00f3ria.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; 5. Escolha termos espec\u00edficos<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; H\u00e1 palavras que s\u00e3o mais espec\u00edficas do que outras. Gato siam\u00eas \u00e9 mais singular do que simplesmente gato; homem, mais do que animal; laranjeira, mais que \u00e1rvore; \u00e1rvore, mais do que planta ou vegetal.&nbsp; Trabalhador \u00e9 termo de sentido geral, muito amplo; jornalista tem sentido mais restrito; jornalista do Correio Braziliense, mais ainda. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Ao descrever uma cena de rua, voc\u00ea pode referir-se genericamente a transeuntes ou particularizar: homens, jovens, estudantes, alunos da Escola Normal.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Escrever Foi um per\u00edodo dif\u00edcil constitui vagueza. Estive desempregado durante tr\u00eas meses \u00e9 mais preciso, bem melhor.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; N\u00e3o foi por acidente que Gon\u00e7alves Dias comp\u00f4s: \u201cMinha terra tem palmeiras \/ Onde canta o sabi\u00e1\u201c. Se tivesse dito Minha terra tem \u00e1rvores \/ Onde canta o p\u00e1ssaro, seus versos estariam enterrados com ele, ignorados de todos.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Siga a regra: o espec\u00edfico \u00e9 prefer\u00edvel ao gen\u00e9rico; o definido ao vago; o concreto ao abstrato.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; 6. Abuse de substantivos e verbos<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Escreva com a convi\u00e7\u00e3o de que no idioma s\u00f3 existem substantivos e verbos. As demais classes de palavras devem ser usadas com o cuidado do ourives e a parcim\u00f4nia do sovina.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; 7. Respeite a harmonia<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; A harmonia est\u00e1 ligada ao ouvido. Implica a habilidade de combinar as palavras e frases com eleg\u00e2ncia, sem trope\u00e7os, ecos, repeti\u00e7\u00f5es ou disson\u00e2ncias. Os rom\u00e2nticos impressionistas dizem que cada um escreve como quer, mas at\u00e9 eles reconhecem que a harmonia \u00e9 o segredo dos grandes escritores, qualidade essencial do estilo. Por isso, leve em conta estes princ\u00edpios:<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; a. D\u00ea prioridade ao termo mais curto: Na coloca\u00e7\u00e3o dos termos na ora\u00e7\u00e3o, o mais curto (o que tiver o menor n\u00famero de s\u00edlabas) deve preceder o mais longo:. Na livraria, comprei uma gram\u00e1tica, um dicion\u00e1rio e v\u00e1rios livros de geografia e hist\u00f3ria \u00e9 constru\u00e7\u00e3o prefer\u00edvel a Na livraria, comprei v\u00e1rios livros de geografia e hist\u00f3ria, uma gram\u00e1tica e um dicion\u00e1rio.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp;&nbsp; Examine outros exemplos: O Mustang volta ao Brasil com tecnologia e desenho modernos por R$ 39mil (n\u00e3o: O Mustang volta com tecnologia e desenhos modernos por R$ 69 mil ao Brasil).&nbsp; Gl\u00e1uber Rocha, diretor dos filmes Deus e o Diabo na Terra do Sol&nbsp; e Terra em Transe, foi homenageado no festival (\u00e9 prefer\u00edvel a: O diretor dos filmes Deus e o Diabo na Terra do Sol e Terra em Transe, Gl\u00e1uber Rocha, foi homenageado no festival). O Congresso Nacional votar\u00e1 o projeto na pr\u00f3xima semana em regime de urg\u00eancia urgent\u00edssima (nunca: O Congresso Nacional voltar\u00e1, na pr\u00f3xima semana em regime de urg\u00eancia urgent\u00edssima, o projeto).<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; b. Evite os ecos: A rima, qualidade da poesia, \u00e9 considerada defeito da prosa. Releia seus textos, de prefer\u00eancia em voz alta, para verificar se ocorre repeti\u00e7\u00e3o de sons iguais ou semelhantes: Mais confus\u00e3o e provoca\u00e7\u00e3o no Maranh\u00e3o. O Plano Real acabou com a infla\u00e7\u00e3o inercial. O rigor do calor de Salvador lhe causava maior pavor.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; c. Cuidado com as cacofonias: \u00c0s vezes, a \u00faltima s\u00edlaba de uma palavra se junta \u00e0 primeira de outra e forma novo voc\u00e1bulo, soando desagradavelmente aos ouvidos do leitor atento ou desavisado: por cada; uma m\u00e3o; por raz\u00f5es, boca dela, por tal, por tais, por t\u00e3o.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; d. Fuja da monotonia: As repeti\u00e7\u00f5es, seja de palavras, seja de estruturas, s\u00e3o as grandes respons\u00e1veis pela monotonia do texto, transmitem a impress\u00e3o de inexperi\u00eancia , descuido e pobreza de vocabul\u00e1rio. Existem formas de evit\u00e1-las. 1) suprimir a palavra; 2) substitu\u00ed-la por sin\u00f4nimo ou pronome; e 3) dar outro torneio \u00e0 frase.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp;&nbsp; 8. Aproxime termos e ora\u00e7\u00f5es que se relacionem pelo sentido<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; A liberdade de coloca\u00e7\u00e3o de termos na frase e ora\u00e7\u00f5es no per\u00edodo encontra limites nas exig\u00eancias da clareza e da coer\u00eancia. A boa norma manda \u201camarrar\u201ccada termo determinante ao respectivo termo determinado.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Haver\u00e1 um semin\u00e1rio sobre Aids na C\u00e2mara dos Deputados.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; O semin\u00e1rio se realizar\u00e1 na C\u00e2mara, mas a coloca\u00e7\u00e3o do adjunto adverbial&nbsp; na C\u00e2mara dos Deputados junto do termo Aids leva a outra leitura: o semin\u00e1rio tratar\u00e1 da ocorr\u00eancia de Aids na C\u00e2mara dos Deputados.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Evita-se a ambig\u00fcidade aproximando o adjunto adverbial do termo a que se refere: Na C\u00e2mara dos Deputados, haver\u00e1 um semin\u00e1rio sobre Aids.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; 9. D\u00ea clareza \u00e0s declara\u00e7\u00f5es <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Dificultar a compreens\u00e3o do texto \u00e9 colocar uma pedra no caminho do leitor. Para que obrig\u00e1-lo a gastar tempo e energia na transposi\u00e7\u00e3o do obst\u00e1culo? Facilite-lhe a passagem. Nas declara\u00e7\u00f5es longas, n\u00e3o o deixe ansioso. Identifique o autor imediatamente \u2013&nbsp; antes da cita\u00e7\u00e3o ou depois da primeira frase. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Veuillot ensina: \u201c\u00c9 preciso escrever com a convic\u00e7\u00e3o de que s\u00f3 h\u00e1 duas palavras no idioma: o substantivo e o verbo. Ponhamo-nos em guarda contra as outras palavras\u201c.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ou<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; \u201c\u00c9 preciso escrever com a convic\u00e7\u00e3o de que s\u00f3 existem duas palavras no idioma: o substantivo e o verbo\u201c, ensina Veuillot. \u201cPonhamo-nos em guarda contra as outras palavras.\u201c<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Nas declara\u00f5es curtas, a identifica\u00e7\u00e3o do autor pode ser feita no come\u00e7o ou no fim da fala:<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; \u201cToda quest\u00e3o tem dois lados\u201c, escreveu Pit\u00e1goras.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Pit\u00e1goras escreveu: \u201cToda quest\u00e3o tem dois lados\u201c. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp;&nbsp; 10. Seja conciso<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Cultivar a economia verbal sem preju\u00edzo da completa e eficaz express\u00e3o do pensamento tem dupla vantagem: respeita a paci\u00eancia do leitor e poupa tempo e espa\u00e7o (bens escassos no jornal).<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Conciso n\u00e3o significa lac\u00f4nico, mas denso. Op\u00f5e-se a vago, impreciso, verborr\u00e1gico. No estilo denso, cada palavra, cada frase, cada par\u00e1grafo devem estar impregnados de sentido.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Eis algumas sugest\u00f5es que contribuem para a concis\u00e3o:<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; a. Dispense, nas datas, os substantivos dia, m\u00eas e ano: em 20 de janeiro (n\u00e3o no dia 20 de janeiro); em dezembro (n\u00e3o no m\u00eas de dezembro); em 1995 (n\u00e3o no ano de 1995).<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; b. Substitua a locu\u00e7\u00e3o adjetiva por adjetivo: material de guerra ( material b\u00e9lico); pessoa sem discri\u00e7\u00e3o (pessoa indiscreta).<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; c. Troque a ora\u00e7\u00e3o adjetiva por adjetivo: animal que se alimenta de carne (animal carn\u00edvoro); pessoa que planta caf\u00e9 (cafeicultor); crian\u00e7a que n\u00e3o tem educa\u00e7\u00e3o (crian\u00e7a mal-educada).<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; d. Use aposto nominal em vez de ora\u00e7\u00e3o apositiva: Bras\u00edlia, que \u00e9 a capital do Brasil, oferece servi\u00e7os p\u00fablicos de boa qualidade (Bras\u00edlia, capital do Brasil, oferece servi\u00e7os p\u00fablicos de boa qualidade). Jarbas Passarinho, que foi eleito senador pelo Par\u00e1, nasceu no Acre (Jarbas Passarinho, eleito senador pelo Par\u00e1, nasceu no Acre). Jac\u00f3 amou Raquel, que era a a filha mais nova de Lab\u00e3o (Jac\u00f3 amou Raquel, a filha mais nova de Lab\u00e3o).<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; e. Substitua a ora\u00e7\u00e3o pelo termo nominal correspondente:<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; A comunidade exige que o criminoso seja punido (a puni\u00e7\u00e3o do criminoso). Ningu\u00e9m duvidava que o plano tivesse \u00eaxito (do \u00eaxito do plano) .<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp;&nbsp; f. Reduza ora\u00e7\u00f5es:<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Agora que expliquei o t\u00edtulo, passo a escrever o livro (Explicado o t\u00edtulo, passo a escrever o livro).<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; Depois de redigir o texto, pensarei na legenda (Redigido o texto, pensarei na legenda).<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp; g. Elimine palavras ou express\u00f5es desnecess\u00e1rias: decis\u00e3o tomada no \u00e2mbito da diretoria (decis\u00e3o da diretoria); trabalho de natureza tempor\u00e1ria (trabalho tempor\u00e1rio); problema de ordem emocional (problema emocional); curso em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o (curso de p\u00f3s-gradua\u00e7\u00e3o); lei de alcance federal (lei federal); doen\u00e7a de caracter\u00edstica sexual (doen\u00e7a sexual); casos de ocorr\u00eancia (ocorr\u00eancias); casos de atraso (atrasos).<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; h. Substitua a locu\u00e7\u00e3o verbo + substantivo pelo verbo: Fazer uma viagem (viajar). Fazer m\u00fasica (compor). P\u00f4r as id\u00e9ias em ordem (ordenar as id\u00e9ias). P\u00f4r moedas em circula\u00e7\u00e3o (emitir moedas).<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">6<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp; &nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;\u201cO estilo deve ter tr\u00eas virtudes: clareza, clareza eclareza.&#8221;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;Anatole France &nbsp;&nbsp;&nbsp; N\u00f3s escrevemos para o leitor. Queremos que ele leia e entenda&nbsp; nosso texto.&nbsp; E&nbsp; mais: que aprecie a leitura, que n\u00e3o se arrependa da escolha. Os cinco, dez ou vinte minutos investidos no artigo, reportagem ou entrevista devem ter retorno [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3006","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=3006"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/3006\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=3006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=3006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=3006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}