{"id":2987,"date":"2008-12-02T14:05:00","date_gmt":"2008-12-02T16:05:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e_agora_houaiss\/"},"modified":"2008-12-02T14:05:00","modified_gmt":"2008-12-02T16:05:00","slug":"e_agora_houaiss","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e_agora_houaiss\/","title":{"rendered":"E agora, Houaiss?"},"content":{"rendered":"<p><b> <\/p>\n<p><\/b>  <\/p>\n<p>Jos\u00e9 Gomes Pimenta tem olhos pra ver e mem\u00f3ria pra reter.  Professor de portugu\u00eas em Divin\u00f3polis, goza de velha amizade com dicion\u00e1rios.  Freq\u00fcenta-os sem cerim\u00f4nia v\u00e1rias vezes ao dia. N\u00e3o raro acorda no meio da noite  pra sanar d\u00favida que pintou no meio do sono. Tanta intimidade levou-o a acredita  que tr\u00eas coisas n\u00e3o podem falhar: o amante no encontro amoroso, a luz em sala de  cirurgia e\u2026 o dicion\u00e1rio.   <\/p>\n<p>Outro dia, descobriu o inimagin\u00e1vel. O <i>Houaiss<\/i> lhe  jogou as certezas ao r\u00e9s do ch\u00e3o. Falhou. Na p\u00e1g. 81, ao tratar do verbo  adequar, diz: &#8220;conjug\u00e1vel nas formas arrizot\u00f4nicas, \u00e9 defectivo no presente do  indicativo e do subjuntivo e no imperativo afirmativo e negativo (s\u00f3 1\u00aa e 2\u00aa  pessoas do plural)&#8221;. Na p\u00e1g. 1.252, no verbete <i>estere\u00f3tipo<\/i>, d\u00e1 o golpe de  miseric\u00f3rdia: &#8220;algo que se adequa a um padr\u00e3o fixo ou geral&#8221;. <\/p>\n<p>  \u2014 Que incoer\u00eancia!, exclamou o professor Pimenta. O paiz\u00e3o  ensina uma coisa, mas pratica outra. Joga no time do fa\u00e7a o que eu digo, n\u00e3o o  que fa\u00e7o. Como \u00e9 que pode?<b> <\/b><b>&nbsp;<\/b> <b>Verbo trai\u00e7oeiro<\/b>  <\/p>\n<p>Eta verbo complicado! Advogados, jornalistas, pol\u00edticos,  estudantes, todos trope\u00e7am nele. Ningu\u00e9m escapa. Nem o <i>Aur\u00e9lio<\/i>. Na  primeira edi\u00e7\u00e3o do dicion\u00e1rio, o mestre trombou na conjuga\u00e7\u00e3o do danadinho. Mas,  sabido, corrigiu a bobeira na segunda.   <\/p>\n<p>Explica-se a confus\u00e3o. O adequar \u00e9 daqueles verbos pra l\u00e1 de  especiais. Sovina, s\u00f3 se conjuga nas formas arrizot\u00f4nicas. Em bom portugu\u00eas: nas  formas em que a vogal t\u00f4nica cai depois do <i>qu<\/i>.  <\/p>\n<p>Eis algumas: o pret\u00e9rito perfeito (adeq\u00fcei, adequaste,  adequou, adequamos, adequastes, adequaram); o imperfeito (adequava, adequavas,  adequava, adequ\u00e1vamos, adequ\u00e1veis, adequavam); os futuros do presente e do  pret\u00e9rito (adequarei, adequar\u00e1s, adequar\u00e1; adequaria, adequarias).  <\/p>\n<p>A armadilha est\u00e1 no presente do indicativo. Foi nele que o  Houaiss bateu. Sovina, o tempo do aqui e agora s\u00f3 tem duas pessoas: adequamos e  adequais. &#8220;Adequa&#8221; n\u00e3o tem vez nem a pedido dos deuses do Olimpo.<b>  <\/p>\n<p>Dica<\/b> Voc\u00ea sabe: o diabo \u00e9 perigoso n\u00e3o por ser diabo, mas por ser sabido. Entre no time dele. Fuja  do verbo trai\u00e7oeiro. N\u00e3o o use. Ou use-o com auxiliar: <i>vou adequar, posso  adequar, tento adequar.<\/i> &nbsp;<b><\/b> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jos\u00e9 Gomes Pimenta tem olhos pra ver e mem\u00f3ria pra reter. Professor de portugu\u00eas em Divin\u00f3polis, goza de velha amizade com dicion\u00e1rios. Freq\u00fcenta-os sem cerim\u00f4nia v\u00e1rias vezes ao dia. N\u00e3o raro acorda no meio da noite pra sanar d\u00favida que pintou no meio do sono. Tanta intimidade levou-o a acredita que tr\u00eas coisas n\u00e3o podem falhar: o amante no encontro amoroso, a luz em sala [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2987","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2987"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2987\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}