{"id":2975,"date":"2008-12-01T00:08:00","date_gmt":"2008-12-01T02:08:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/como_e-6\/"},"modified":"2008-12-01T00:08:00","modified_gmt":"2008-12-01T02:08:00","slug":"como_e-6","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/como_e-6\/","title":{"rendered":"Como \u00e9?"},"content":{"rendered":"<p>  &nbsp; Mais de u m leva o verbo para o singular ou plural? Para o singular. Sempre: Mais de um candidato passou no concurso. Mais de um convidado saiu antes do fim da festa. Mais de uma moeda foi perdida.&nbsp; <BR><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Mais de u m leva o verbo para o singular ou plural? Para o singular. Sempre: Mais de um candidato passou no concurso. Mais de um convidado saiu antes do fim da festa. Mais de uma moeda foi perdida.&nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2975","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2975"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2975\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}