{"id":2962,"date":"2008-11-28T01:00:00","date_gmt":"2008-11-28T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e_assim-5\/"},"modified":"2008-11-28T01:00:00","modified_gmt":"2008-11-28T03:00:00","slug":"e_assim-5","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e_assim-5\/","title":{"rendered":"\u00c9 assim"},"content":{"rendered":"<p>&nbsp;   <\/p>\n<p>Sem-n\u00famero se escreve assim. As duas palavras querem dizer n\u00famero indeterminado, grande quantidade: Na viagem, comprei um sem-n\u00famero de lembrancinhas. O governador respondeu a um sem-n\u00famero de eleitores. T odos os anos, as enchentes deixam um sem-n\u00famero de desabrigados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Sem-n\u00famero se escreve assim. As duas palavras querem dizer n\u00famero indeterminado, grande quantidade: Na viagem, comprei um sem-n\u00famero de lembrancinhas. O governador respondeu a um sem-n\u00famero de eleitores. T odos os anos, as enchentes deixam um sem-n\u00famero de desabrigados.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2962","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2962"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2962\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}