{"id":2920,"date":"2008-11-19T09:40:00","date_gmt":"2008-11-19T11:40:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/tem_crase\/"},"modified":"2008-11-19T09:40:00","modified_gmt":"2008-11-19T11:40:00","slug":"tem_crase","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/tem_crase\/","title":{"rendered":"Tem crase?"},"content":{"rendered":"\n<p>      &#8220;Rumo a 2009.&#8221; O a pede o acento indicativo de crase? A d\u00favida \u00e9 do Jo\u00e3o Marcelo. A resposta: n\u00e3o. Crase \u00e9 como alian\u00e7a no anular esquerdo. Indica  o casamento de dois aa. Um \u00e9 a preposi\u00e7\u00e3o. O outro, geralmente, o artigo.  Ora, 2009 \u00e9 numeral. N\u00e3o pede artigo. N\u00e3o pode, pois, haver  crase.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Rumo a 2009.&#8221; O a pede o acento indicativo de crase? A d\u00favida \u00e9 do Jo\u00e3o Marcelo. A resposta: n\u00e3o. Crase \u00e9 como alian\u00e7a no anular esquerdo. Indica o casamento de dois aa. Um \u00e9 a preposi\u00e7\u00e3o. O outro, geralmente, o artigo. Ora, 2009 \u00e9 numeral. N\u00e3o pede artigo. N\u00e3o pode, pois, haver crase.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2920","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2920"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2920\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}