{"id":2886,"date":"2008-11-12T12:00:00","date_gmt":"2008-11-12T14:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/virgem_maria\/"},"modified":"2008-11-12T12:00:00","modified_gmt":"2008-11-12T14:00:00","slug":"virgem_maria","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/virgem_maria\/","title":{"rendered":"Virgem Maria!"},"content":{"rendered":"<p>&nbsp;<br \/>\n&nbsp;<br \/>\nRafael adora assistir ao programa Pelo Mundo, da GloboNews. No domingo fez o que faz todas as semanas. Ligou a tev\u00ea pra ver as novidades. Foi um susto atr\u00e1s do outro. &#8220;Novidades \u00e0 cavalo&#8221;, apareceu grafado na telinha. &#8220;H\u00e1 ping\u00fcins maus car\u00e1teres&#8221;, anunciou em seguida a charmosa apresentadora.<\/p>\n<p>&nbsp;<br \/>\nNo primeiro caso, Rafael n\u00e3o teve d\u00favida. Desde que Ad\u00e3o e Eva usavam fraldas, n\u00e3o ocorre crase antes de nome masculino. O acento, portanto, sobra. No segundo caso, pintou a d\u00favida. Qual o plural de car\u00e1ter? Consultou o dicion\u00e1rio e a gram\u00e1tica. L\u00e1 estava caracteres. A s\u00edlaba t\u00f4nica? \u00c9 te.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Rafael adora assistir ao programa Pelo Mundo, da GloboNews. No domingo fez o que faz todas as semanas. Ligou a tev\u00ea pra ver as novidades. Foi um susto atr\u00e1s do outro. &#8220;Novidades \u00e0 cavalo&#8221;, apareceu grafado na telinha. &#8220;H\u00e1 ping\u00fcins maus car\u00e1teres&#8221;, anunciou em seguida a charmosa apresentadora. &nbsp; No primeiro caso, Rafael n\u00e3o teve d\u00favida. Desde que Ad\u00e3o e Eva usavam fraldas, [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2886","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2886"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2886\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}