{"id":2876,"date":"2008-11-11T14:00:00","date_gmt":"2008-11-11T16:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_super-homem\/"},"modified":"2008-11-11T14:00:00","modified_gmt":"2008-11-11T16:00:00","slug":"o_super-homem","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o_super-homem\/","title":{"rendered":"O super-homem"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/blogs.correiobraziliense.com.br\/wp-content\/uploads\/blog-dad\/51e72a91dcdc3455a8580fb671d879c9.jpg\"><br \/>\n&nbsp;<br \/>\n&#8220;Pode esse homem salvar a Am\u00e9rica e o mundo?&#8221;, pergunta a capa da <I>Isto \u00e9<\/I> que est\u00e1 nas bancas. O leitor olha, p\u00e1ra e pensa. O pronome <I>esse<\/I> est\u00e1 correto? Ou seria a vez do <I>este<\/I>?<br \/>\n&nbsp;<br \/>\nO demonstrativo, no caso, indica situa\u00e7\u00e3o no texto. O <I>esse<\/I> diz que a pessoa j\u00e1 foi referida. Foi? Foi. Acima est\u00e1 a informa\u00e7\u00e3o: &#8220;Barac Obama, presidente eleito dos Estados Unidos&#8221;. <B><br \/>\n&nbsp;<\/B><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &#8220;Pode esse homem salvar a Am\u00e9rica e o mundo?&#8221;, pergunta a capa da Isto \u00e9 que est\u00e1 nas bancas. O leitor olha, p\u00e1ra e pensa. O pronome esse est\u00e1 correto? Ou seria a vez do este? &nbsp; O demonstrativo, no caso, indica situa\u00e7\u00e3o no texto. O esse diz que a pessoa j\u00e1 foi referida. Foi? Foi. Acima est\u00e1 a informa\u00e7\u00e3o: &#8220;Barac Obama, presidente eleito [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2876","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2876"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2876\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}