{"id":2874,"date":"2008-11-11T00:00:00","date_gmt":"2008-11-11T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/de_regras_e_excecoes\/"},"modified":"2008-11-11T00:00:00","modified_gmt":"2008-11-11T02:00:00","slug":"de_regras_e_excecoes","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/de_regras_e_excecoes\/","title":{"rendered":"De regras e exce\u00e7\u00f5es"},"content":{"rendered":"<p>&nbsp;<br \/>\n&nbsp;<br \/>\n&#8220;O&nbsp;verbo concorda com o sujeito em pessoa e n\u00famero&#8221;, diz a regra.&nbsp;Em outras palavras: aonde o sujeito vai, o verbo vai atr\u00e1s. Refresque a mem\u00f3ria: Eu estudo franc\u00eas; Maria prefere russo. N\u00f3s trabalhamos das 8h \u00e0s 18h. Eles passaram no teste.<br \/>\n&nbsp;<br \/>\nMas, na gram\u00e1tica como na vida, nem todos s\u00e3o iguais perante a lei. Alguns s\u00e3o mais iguais. \u00c9 o caso da ex press\u00e3o &#8220;\u00e9 suficiente&#8221;. Ardilosa, a sabida ridiculariza autoridades, desclassifica candidatos, mata amores. Pior: confunde a cabe\u00e7a dos pobres mortais. Com ela, todo o cuidado \u00e9 pouco.<br \/>\n&nbsp;<br \/>\nSe o sujeito d\u00e1 id\u00e9ia de pre\u00e7o, peso, medida, valor ou quantidade, o verbo fica no singular. N\u00e3o se flexiona nem a pedido de Deus: Quer ver? Trinta cadeiras \u00e9 suficiente. Quinze reais \u00e9 suficiente para pagar os ingressos. Dois quilos de carne \u00e9 suficiente para fazer o churrasco. Trinta mil reais foi suficiente para contratar todos os assessores.<br \/>\n&nbsp;<br \/>\nAten\u00e7\u00e3o, muita aten\u00e7\u00e3o. \u00c0s vezes, o numeral vem acompanhado. A\u00ed cessa tudo que a musa antiga canta. Se ele estiver antecedido de artigo ou pronome, pronto. Volta a democracia. O verbo se torna igual aos mortais. Concorda com o sujeito:&nbsp;Os 28% de aumento concedidos aos funcion\u00e1rios p\u00fablicos s\u00e3o insuficientes. Quaisquer cinco reais s\u00e3o suficientes para pagar o estacionamento. Uns cinco quilos a mais seriam suficientes para ela recuperar o peso.<br \/>\n&nbsp;<br \/>\n\u00c9 isso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &#8220;O&nbsp;verbo concorda com o sujeito em pessoa e n\u00famero&#8221;, diz a regra.&nbsp;Em outras palavras: aonde o sujeito vai, o verbo vai atr\u00e1s. Refresque a mem\u00f3ria: Eu estudo franc\u00eas; Maria prefere russo. N\u00f3s trabalhamos das 8h \u00e0s 18h. Eles passaram no teste. &nbsp; Mas, na gram\u00e1tica como na vida, nem todos s\u00e3o iguais perante a lei. Alguns s\u00e3o mais iguais. \u00c9 o caso da [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2874","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2874"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2874\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}