{"id":2844,"date":"2008-11-05T10:00:00","date_gmt":"2008-11-05T12:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/ou_ou\/"},"modified":"2008-11-05T10:00:00","modified_gmt":"2008-11-05T12:00:00","slug":"ou_ou","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/ou_ou\/","title":{"rendered":"Ou, ou"},"content":{"rendered":"<p><B><BR><\/B><br \/>\n<BR><br \/>\nJorginho de Souza, de Olinda, pergunta: &#8220;A conjun\u00e7\u00e3o <B>ou<\/B> me confunde sempre. Com sujeitos ligados por ela, quando o verbo vai para o singular ou para o plural?&#8221;<B><br \/>\n<BR><\/B><br \/>\nInterprete o recado. O <I>ou<\/I> indica exclus\u00e3o? \u00c9 a vez do singular: Obama ou McCain ser\u00e1 presidente dos Estados Unidos. (S\u00f3 h\u00e1 uma vaga de presidente. O <I>ou<\/I> elimina um dos pretendentes.)<br \/>\n<BR><br \/>\nO ou inclui? D\u00ea passagem ao plural: Um ou outro brasileiro compareceram \u00e0 festa na embaixada americana. (Na festa h\u00e1 lugar para mais de um brasileiro.)<br \/>\n<DIV>&nbsp;<\/DIV><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jorginho de Souza, de Olinda, pergunta: &#8220;A conjun\u00e7\u00e3o ou me confunde sempre. Com sujeitos ligados por ela, quando o verbo vai para o singular ou para o plural?&#8221; Interprete o recado. O ou indica exclus\u00e3o? \u00c9 a vez do singular: Obama ou McCain ser\u00e1 presidente dos Estados Unidos. (S\u00f3 h\u00e1 uma vaga de presidente. O ou elimina um dos pretendentes.) O ou inclui? D\u00ea passagem [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2844","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2844"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2844\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}