{"id":2836,"date":"2008-11-04T00:00:00","date_gmt":"2008-11-04T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/culpa_da_preposicao\/"},"modified":"2008-11-04T00:00:00","modified_gmt":"2008-11-04T02:00:00","slug":"culpa_da_preposicao","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/culpa_da_preposicao\/","title":{"rendered":"Culpa da preposi\u00e7\u00e3o"},"content":{"rendered":"<p>&nbsp;<br \/>\n&nbsp;<br \/>\nTempos atr\u00e1s ca\u00edram as vendas do Caf\u00e9 Export. Foi um deus-nos-acuda. &#8220;O que aconteceu?&#8221;, perguntavam-se todos. A empresa havia feito uma cara campanha publicit\u00e1ria. A propaganda invadiu as ruas. Havia outdoors por todos os lados. Os an\u00fancios concentraram-se nas proximidades dos supermercados.<br \/>\n&nbsp;<br \/>\nO cliente, ao ir \u00e0s compras, batia os olhos no texto: &#8220;Caf\u00e9 Export.O gosto que eu gosto&#8221;. A\u00ed a porca torcia o rabo. Os consumidores paravam diante da frase. Algo soava mal. Nem todos identificavam a falha. Mas achavam melhor n\u00e3o arriscar. Partiam pra outra marca.<br \/>\n&nbsp;<br \/>\nResultado: a campanha fez \u00e1gua. Degringolou. A culpa? \u00c9 da preposi\u00e7\u00e3o sim, senhor.&nbsp;Trata-se do emprego do pronome relativo. Mais precisamente: do pronome relativo antecedido de preposi\u00e7\u00e3o. O danado \u00e9 espinho no p\u00e9 de muita gente. A raz\u00e3o: os relativos detestam repeti\u00e7\u00f5es. Elegant\u00edssimos, d\u00e3o grande ajuda a quem escreve. Substituem o termo repetido.<br \/>\n&nbsp;<br \/>\nComprei o <STRONG>rem\u00e9dio<\/STRONG>. O <STRONG>rem\u00e9dio<\/STRONG> se chama Luftal.<br \/>\n&nbsp;<br \/>\nFeio, n\u00e3o? O termo dose dupla \u00e9 rem\u00e9dio. Para n\u00e3o escrev\u00ea -lo duas vezes, o relativo entra em a\u00e7\u00e3o:<br \/>\n&nbsp;<br \/>\nComprei o rem\u00e9dio <STRONG>que<\/STRONG> se chama Luftal.<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n<STRONG>Mais exemplos:<\/STRONG><br \/>\n&nbsp;<br \/>\nMoro na <STRONG>cidade<\/STRONG>. Voc\u00ea conhece a <STRONG>cidade<\/STRONG>.<br \/>\n&nbsp;<br \/>\nO termo repetido \u00e9 cidade. Azar dele. Est\u00e1 condenado \u00e0 substitui\u00e7\u00e3o: Moro na cidade <STRONG>que<\/STRONG> voc\u00ea conhece.<br \/>\n&nbsp;<br \/>\n<STRONG>\u00cdris<\/STRONG> era irm\u00e3 do governador. <STRONG>\u00cdris<\/STRONG> morreu num acidente de helic\u00f3ptero. (\u00cdris, <STRONG>que<\/STRONG> morreu num acidente de helic\u00f3ptero, era irm\u00e3 do governador.)<br \/>\n&nbsp;<br \/>\nA cidade se chama <STRONG>Recife<\/STRONG>. Moro em <STRONG>Recife<\/STRONG>. (A cidade <STRONG>onde<\/STRONG> moro se chama Recife.)<br \/>\n&nbsp;<br \/>\nO <STRONG>autor<\/STRONG> trabalha em Jo\u00e3o Pessoa. A obra do <STRONG>autor<\/STRONG> foi premiada.(O autor <STRONG>cuja<\/STRONG> obra foi premiada trabalha em Jo\u00e3o P essoa).<br \/>\n&nbsp;<br \/>\n<STRONG><\/STRONG>&nbsp;<br \/>\n<STRONG>Companhia<\/STRONG><br \/>\n&nbsp;<br \/>\nE a preposi\u00e7\u00e3o? Ela s\u00f3 aparece quando o verbo pedir companhia. Ou seja, pedir preposi\u00e7\u00e3o. \u00c9 o caso de gostar (de), obedecer (a), falar (de), lutar (por). Se o termo repetido estiver antecedido de preposi\u00e7\u00e3o, abra o olho. O pronome n\u00e3o a substitui. A preposi\u00e7\u00e3o fica no lugarzinho dela &#8212;&nbsp;antes do relativo.<br \/>\n&nbsp;<br \/>\nO livro se chama Vidas Secas. Gosto <STRONG>do<\/STRONG> livro. (O livro de que gosto se chama Vidas Secas.)<br \/>\n&nbsp;<br \/>\nEste \u00e9 o regulamento. Obede\u00e7o <STRONG>a<\/STRONG>o regulamento. (Este \u00e9 o regulamento <STRONG>a<\/STRONG> que obede\u00e7o.)<br \/>\n&nbsp;<br \/>\nA pessoa mora no Rio. Falei <STRONG>da<\/STRONG> pessoa. (A pessoa <STRONG>de<\/STRONG> que falei mora no Rio.)<br \/>\n&nbsp;<br \/>\nOs trabalhadores lutam <STRONG>por<\/STRONG> empregos. Os empregos est\u00e3o desaparecendo. (Os empregos <STRONG>por<\/STRONG> que os trabalhadores lutam est\u00e3o desaparecendo.)<br \/>\n&nbsp;<br \/>\nA cidade ficou alagada. Vim <STRONG>da<\/STRONG> cidade. (A cidade <STRONG>de<\/STRONG> onde vim ficou alagada.)<br \/>\n&nbsp;<br \/>\n<STRONG><\/STRONG>&nbsp;<br \/>\n<STRONG>O caf\u00e9 de que gosto<\/STRONG><br \/>\n&nbsp;<br \/>\nFoi essa a li\u00e7\u00e3o que o publicit\u00e1rio do Caf\u00e9 Export n\u00e3o aprendeu. Desmembrada, a frase ficaria assim:<br \/>\n&nbsp;<br \/>\nCaf\u00e9 Export (tem) o gosto. Eu gosto <STRONG>do<\/STRONG> gosto. (Caf\u00e9 Export tem o gosto <STRONG>de<\/STRONG> que eu gosto. Caf\u00e9 Export. O gosto <STRONG>de<\/STRONG> que eu gosto.)<br \/>\n&nbsp;<br \/>\nReparou? Gosto \u00e9 o termo repetido. O pronome relativo o substituiu. E a preposi\u00e7\u00e3o de? O an\u00fancio a engoliu. Ai, indigest\u00e3o!&nbsp;<BR>&nbsp;<BR><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Tempos atr\u00e1s ca\u00edram as vendas do Caf\u00e9 Export. Foi um deus-nos-acuda. &#8220;O que aconteceu?&#8221;, perguntavam-se todos. A empresa havia feito uma cara campanha publicit\u00e1ria. A propaganda invadiu as ruas. Havia outdoors por todos os lados. Os an\u00fancios concentraram-se nas proximidades dos supermercados. &nbsp; O cliente, ao ir \u00e0s compras, batia os olhos no texto: &#8220;Caf\u00e9 Export.O gosto que eu gosto&#8221;. A\u00ed a porca [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2836","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2836"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2836\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}