{"id":2828,"date":"2008-10-30T10:05:00","date_gmt":"2008-10-30T12:05:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/os_breves\/"},"modified":"2008-10-30T10:05:00","modified_gmt":"2008-10-30T12:05:00","slug":"os_breves","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/os_breves\/","title":{"rendered":"Os breves"},"content":{"rendered":"<p><BR><BR>A fam\u00edlia pertence ao cl\u00e3 dos impacientes.&nbsp; Abreviar \u00e9 um dos seus membros. Brevi\u00e1rio, outro. Abreviatura, mais um. T odos s\u00e3o filhos do mesmo pai. Ele se chama breve. A diss\u00edlaba significa de pouca dura\u00e7\u00e3 o ou de pouca extens\u00e3o ou tamanho. Op\u00f5e-se a comprido, extenso, prolixo. <BR><BR>A l\u00edngua denuncia o falante. Se ele tem \u00e2nsia de brevidade,&nbsp; ela n\u00e3o o deixa na m\u00e3o. Colabora. Por isso, inventou as&nbsp; abreviaturas.&nbsp;Com elas, reduz um palavr\u00e3o a poucas letras. Doutor vira&nbsp; dr. Apartamento, ap. Quil\u00f4metro, km. <BR><BR>Nada \u00e9 de gra\u00e7a. Paga-se um pre\u00e7o pela ajuda. S\u00e3o as regras para usar as pequeninas. A mais importante: ter pena do leitor. A redu\u00e7\u00e3o n\u00e3o deve confundi-lo. Precisa ser familiar, facilmente entendida.<BR><BR><BR>Outras normas:<BR><BR><BR>As abreviaturas formadas pela diminui\u00e7\u00e3o de palavras t\u00eam duas manhas. Uma: exigem o ponto final. A outra: n\u00e3o abrem m\u00e3o do s do plural: caps., p\u00e1gs., cias.<BR><BR><BR>Na l\u00edngua como na vida, alguns s\u00e3o mais iguais perante a abreviatura. \u00c9 o caso de hora, minuto, segundo, metro, quilo, litro e respectivos derivados (quil\u00f4metro, mililitro). Eles s\u00e3o sem-sem. Dispensam o ponto abreviativo e o s indicador de plural: 5h30, 3h30min14 , 4,5m, 20k g, 10ml. <BR><BR>Mais: as pequeninas respeitam a origem. Se a compridona tem acento, a reduzida o<BR>mant\u00e9m no lugarzinho dele: s\u00e9culo&nbsp; (s\u00e9c.), p\u00e1gina (p\u00e1g.) , t\u00edtulo ( t\u00edt.) , c\u00f3digo (c\u00f3d.).<BR><BR><BR>X\u00f4, praga<BR><BR><BR>Pragas aparecem de vez em quando. As abreviaturas n\u00e3o est\u00e3o imunes a&nbsp; elas. A mais recente atingiu a nobre figura do professor. Todos os manuais dizem que a abreviatura do mestre \u00e9 prof. Mas, por alguma raz\u00e3o alheia \u00e0 vontade de Deus e dos homens, come\u00e7aram a brind\u00e1-lo com um ozinho (prof\u00ba ). O intruso aparece at\u00e9 em cartazes de faculdade. D\u00e1 raiva.<BR><BR><BR>A l\u00edngua detesta redund\u00e2ncia. O masculino n\u00e3o precisa do o. O feminino,<BR>sim, pede a. O plural, s. Compare:<BR><BR><BR>professor &#8212; prof.<BR>professores &#8212; profs.<BR>professora &#8212; prof\u00aa<BR>professoras &#8212; prof\u00aas<BR>doutor &#8212; dr.<BR>doutores &#8212; drs.<BR>doutora &#8212; dra.<BR>doutoras &#8212; dras.<BR><BR><BR>Criaturas chiques<BR><BR>Abreviaturas latinas costumam freq\u00fcentar livros e trabalhos de pesquisas. Voc\u00ea as conhece? Elas s\u00e3o verdadeiras aristocratas. Eis algumas:<BR><BR><BR>ib. ou ibid. . ibidem (no mesmo lugar)<BR>id. . idem (o mesmo)<BR>op. cit. . opus citatum (obra citada)<BR>pass. . passim (aqui e ali, em diversos lugares)<BR><BR><BR><BR><BR><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A fam\u00edlia pertence ao cl\u00e3 dos impacientes.&nbsp; Abreviar \u00e9 um dos seus membros. Brevi\u00e1rio, outro. Abreviatura, mais um. T odos s\u00e3o filhos do mesmo pai. Ele se chama breve. A diss\u00edlaba significa de pouca dura\u00e7\u00e3 o ou de pouca extens\u00e3o ou tamanho. Op\u00f5e-se a comprido, extenso, prolixo. A l\u00edngua denuncia o falante. Se ele tem \u00e2nsia de brevidade,&nbsp; ela n\u00e3o o deixa na m\u00e3o. Colabora. [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2828","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2828"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2828\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}