{"id":2822,"date":"2008-10-29T18:00:00","date_gmt":"2008-10-29T20:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-236\/"},"modified":"2015-11-12T16:59:50","modified_gmt":"2015-11-12T18:59:50","slug":"erramos-236","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-236\/","title":{"rendered":"Erramos"},"content":{"rendered":"<p>\u201cIsso n\u00e3o desqualifica e nem qualifica\u201d, escrevemos na p\u00e1g. 4. Observou o desperd\u00edcio manhoso? A conjun\u00e7\u00e3o nem traz embutida a conjun\u00e7\u00e3o e (nem = e n\u00e3o). \u00c9 bom ficar com uma ou outra: Isso n\u00e3o qualifica nem desqualifica. Isso n\u00e3o qualifica e n\u00e3o desqualifica. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cIsso n\u00e3o desqualifica e nem qualifica\u201d, escrevemos na p\u00e1g. 4. Observou o desperd\u00edcio manhoso? A conjun\u00e7\u00e3o nem traz embutida a conjun\u00e7\u00e3o e (nem = e n\u00e3o). \u00c9 bom ficar com uma ou outra: Isso n\u00e3o qualifica nem desqualifica. Isso n\u00e3o qualifica e n\u00e3o desqualifica.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-2822","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2822"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2822\/revisions"}],"predecessor-version":[{"id":10902,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2822\/revisions\/10902"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}