{"id":2800,"date":"2008-10-25T20:00:00","date_gmt":"2008-10-25T22:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/drummond_falou_e_disse\/"},"modified":"2008-10-25T20:00:00","modified_gmt":"2008-10-25T22:00:00","slug":"drummond_falou_e_disse","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/drummond_falou_e_disse\/","title":{"rendered":"Drummond falou e disse"},"content":{"rendered":"<p>&nbsp;<br \/>\n&nbsp;<br \/>\n&#8220;Machado, outros leram da vida um cap\u00edtulo, tu leste o livro inteiro.&#8221;<BR><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &#8220;Machado, outros leram da vida um cap\u00edtulo, tu leste o livro inteiro.&#8221;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2800","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2800"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2800\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}