{"id":2792,"date":"2008-10-24T13:00:00","date_gmt":"2008-10-24T15:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/frater\/"},"modified":"2008-10-24T13:00:00","modified_gmt":"2008-10-24T15:00:00","slug":"frater","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/frater\/","title":{"rendered":"Fr\u00e1ter"},"content":{"rendered":"<p>&nbsp;<br \/>\n&nbsp;<br \/>\n&#8220;Sou membro da antiga e m\u00edstica Ordem Rosa Cruz&#8221;, escreve Ramires Zigunow. &#8220;Usualmente chamamos uns aos outros de fr\u00e1ter (irm\u00e3o). Na hora do plural, alguns dizem fr\u00e1teres. Outros, fr\u00e1ters. Qual a forma correta?&#8221;<br \/>\n&nbsp;<br \/>\nO Aur\u00e9lio registra fr\u00e1teres. Fique com ela.&nbsp;<BR><br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &#8220;Sou membro da antiga e m\u00edstica Ordem Rosa Cruz&#8221;, escreve Ramires Zigunow. &#8220;Usualmente chamamos uns aos outros de fr\u00e1ter (irm\u00e3o). Na hora do plural, alguns dizem fr\u00e1teres. Outros, fr\u00e1ters. Qual a forma correta?&#8221; &nbsp; O Aur\u00e9lio registra fr\u00e1teres. Fique com ela.&nbsp; &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2792","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2792"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2792\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}