{"id":2778,"date":"2008-10-22T19:00:00","date_gmt":"2008-10-22T21:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-231\/"},"modified":"2015-11-12T16:59:54","modified_gmt":"2015-11-12T18:59:54","slug":"erramos-231","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-231\/","title":{"rendered":"Erramos"},"content":{"rendered":"<p>&nbsp;<br \/>\n&nbsp;<br \/>\n&#8220;Segundo o general Figueiredo, Gabeira fez apenas uma visita de cortesia aos militares, o que ser\u00e1 repetido por seu advers\u00e1rio, Eduardo Paes&#8221;, escrevemos na p\u00e1g. 5. Ops! Olha a ambig\u00fcidade do <I>seu. <\/I>O danado permite dupla leitura \u2014 o advers\u00e1rio pode ser de Gabeira ou do general. Melhor: <I>Segundo o general Figueiredo, Gabeira fez apenas uma visita de cortesia aos militares, o que ser\u00e1 repetido por Eduardo Paes, advers\u00e1rio do candidato verde.<\/I><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &#8220;Segundo o general Figueiredo, Gabeira fez apenas uma visita de cortesia aos militares, o que ser\u00e1 repetido por seu advers\u00e1rio, Eduardo Paes&#8221;, escrevemos na p\u00e1g. 5. Ops! Olha a ambig\u00fcidade do seu. O danado permite dupla leitura \u2014 o advers\u00e1rio pode ser de Gabeira ou do general. Melhor: Segundo o general Figueiredo, Gabeira fez apenas uma visita de cortesia aos militares, o que [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-2778","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2778"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2778\/revisions"}],"predecessor-version":[{"id":10907,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2778\/revisions\/10907"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}