{"id":2683,"date":"2008-10-09T17:00:00","date_gmt":"2008-10-09T20:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/direito_de_resposta_do_trema-2\/"},"modified":"2008-10-09T17:00:00","modified_gmt":"2008-10-09T20:00:00","slug":"direito_de_resposta_do_trema-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/direito_de_resposta_do_trema-2\/","title":{"rendered":"Direito de resposta do trema"},"content":{"rendered":"<p>&nbsp;<br \/>\n&nbsp;<br \/>\n&#8220;Prezados,<br \/>\n&nbsp;<br \/>\nN\u00e3o venho aqui encher ling\u00fci\u00e7a nem esbanjar uma eloq\u00fc\u00eancia inconseq\u00fcente. Estou tranq\u00fcilo quanto ao papel que venho desempenhando na sociedade, da qual tenho sido v\u00edtima com freq\u00fc\u00eancia de ataques.<br \/>\n&nbsp;<br \/>\nN\u00e3o sou menino. Vivi e vi muito. Desde 43 que perambulo por estradas e ditongos da vida. Que o diga o U, este grande amigo a quem n\u00e3o me canso de garantir que tenha voz neste mundo de crescente exclus\u00e3o.<br \/>\n&nbsp;<br \/>\nTamb\u00e9m o dia o M\u00fcller, outro grande defensor de minha carreira, bem como todo o nobre povo alem\u00e3o, este sim um apreciador do chucrute, da m\u00fasica cl\u00e1ssica e do leg\u00edtimo trema germ\u00e2nico.<br \/>\n&nbsp;<br \/>\nAo ver decretada assim minha expatria\u00e7\u00e3o, penso nesse povo sem mem\u00f3ria e sem afeto. Desterraram seu \u00faltimo e apaixonado imperador e agora me trocam por kas, d\u00e1blius e ipsilones representantes do imperialismo sax\u00e3o. Sempre suspeitei que minha morte ou ex\u00edlio estavam sendo h\u00e1 d\u00e9cadas tramadas por algu\u00e9m.<br \/>\n&nbsp;<br \/>\nN\u00e3o sabia se pelos comunistas, pelos socialistas, pelos capitalistas ou pelos f\u00e3s de Marylin Manson. Agora eu sei. Foram os d\u00e1blius, esses v\u00eas pervertidos que sempre andam de m\u00e3os dadas, em plena luz do dia. Caracteres pederastas, esses d\u00e1blius. Pederastas e traidores. Quem me l\u00ea sabe se tem a m\u00e3o ensang\u00fcentada.<br \/>\n&nbsp;<br \/>\nMe espanta a hipocrisia desses mesmos abra\u00e7adores de \u00e1rvores e defensores da ecologia e do seq\u00fcestro de carbono tirarem dessa forma o acento e o acalento dos ping\u00fcins. Agora eles t\u00eam de ag\u00fcentar. Por um, por dez ou por cinq\u00fcenta anos. At\u00e9 o fim de tudo. Ver\u00e3o, na pele, a falta de um trema faz, delinq\u00fcentes ortogr\u00e1ficos, seres de \u00edndole eq\u00fcina.<br \/>\n&nbsp;<br \/>\nVou-me. Partirei de volta para o velho mundo, onde ainda h\u00e1 espa\u00e7o para tremas, lamparinas e fados tristes. Saio desta vida para a ubiq\u00fcidade.&#8221;<br \/>\n&nbsp;<br \/>\n(texto encaminhado por Rold\u00e3o Simas Filho)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &#8220;Prezados, &nbsp; N\u00e3o venho aqui encher ling\u00fci\u00e7a nem esbanjar uma eloq\u00fc\u00eancia inconseq\u00fcente. Estou tranq\u00fcilo quanto ao papel que venho desempenhando na sociedade, da qual tenho sido v\u00edtima com freq\u00fc\u00eancia de ataques. &nbsp; N\u00e3o sou menino. Vivi e vi muito. Desde 43 que perambulo por estradas e ditongos da vida. Que o diga o U, este grande amigo a quem n\u00e3o me canso de [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2683","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=2683"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/2683\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=2683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=2683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=2683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}