{"id":24,"date":"2015-01-09T17:00:00","date_gmt":"2015-01-09T17:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/01\/09\/erramos-2\/"},"modified":"2015-11-12T12:17:31","modified_gmt":"2015-11-12T14:17:31","slug":"erramos-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-2\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>&#8220;GDF  paga primeiro sa\u00fade e no dia 14, educa\u00e7\u00e3o&#8221;, escrevemos na capa. Ops! Faltou uma  v\u00edrgula. Melhor: GDF paga primeiro sa\u00fade e, no dia 14,  educa\u00e7\u00e3o.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;GDF paga primeiro sa\u00fade e no dia 14, educa\u00e7\u00e3o&#8221;, escrevemos na capa. Ops! Faltou uma v\u00edrgula. Melhor: GDF paga primeiro sa\u00fade e, no dia 14, educa\u00e7\u00e3o.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-24","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=24"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/24\/revisions"}],"predecessor-version":[{"id":1421,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/24\/revisions\/1421"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=24"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=24"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}