{"id":23702,"date":"2020-10-01T09:03:45","date_gmt":"2020-10-01T12:03:45","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=23702"},"modified":"2020-10-01T09:03:45","modified_gmt":"2020-10-01T12:03:45","slug":"por-que-imortais-sao-imortais","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/por-que-imortais-sao-imortais\/","title":{"rendered":"Por que imortais s\u00e3o imortais"},"content":{"rendered":"<p>As pessoas s\u00f3 morrem quando deixam de ser lembradas. Por isso grandes artistas permanecem vivos gra\u00e7as \u00e0 obra que legaram ao mundo. N\u00e3o por acaso membros da Academia Brasileira de Letras s\u00e3o chamados de imortais. O argentino Quino foi pro c\u00e9u na quarta-feira. Deixou na Terra sua mais preciosa cria\u00e7\u00e3o \u2013 Mafalda, a questionadora garotinha de 6 anos que faz os adultos ficarem com cara de bobos. \u00c9 imortal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As pessoas s\u00f3 morrem quando deixam de ser lembradas. Por isso grandes artistas permanecem vivos gra\u00e7as \u00e0 obra que legaram ao mundo. N\u00e3o por acaso membros da Academia Brasileira de Letras s\u00e3o chamados de imortais. O argentino Quino foi pro c\u00e9u na quarta-feira. Deixou na Terra sua mais preciosa cria\u00e7\u00e3o \u2013 Mafalda, a questionadora garotinha de 6 anos que faz os adultos ficarem com cara [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[4890,4892,4891],"class_list":["post-23702","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-imortal","tag-mafalda","tag-quino"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=23702"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23702\/revisions"}],"predecessor-version":[{"id":23703,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23702\/revisions\/23703"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=23702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=23702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=23702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}