{"id":23520,"date":"2020-09-16T07:49:30","date_gmt":"2020-09-16T10:49:30","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=23520"},"modified":"2020-09-16T07:49:30","modified_gmt":"2020-09-16T10:49:30","slug":"gorjeio-se-escreve-com-j-por-que","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/gorjeio-se-escreve-com-j-por-que\/","title":{"rendered":"Gorjeio se escreve com j: por qu\u00ea?"},"content":{"rendered":"<p>Gon\u00e7alves Dias escreveu: &#8220;Minha terra tem palmeiras \/ Onde canta o sabi\u00e1. \/ As aves que aqui gorjeiam \/N\u00e3o gorjeiam como l\u00e1&#8221;. Por que gorjeio se escreve com j? Gor<strong>j<\/strong>eio se escreve com j porque a letra se parece com o bico do passarinho.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gon\u00e7alves Dias escreveu: &#8220;Minha terra tem palmeiras \/ Onde canta o sabi\u00e1. \/ As aves que aqui gorjeiam \/N\u00e3o gorjeiam como l\u00e1&#8221;. Por que gorjeio se escreve com j? Gorjeio se escreve com j porque a letra se parece com o bico do passarinho. \u00a0 &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[2543,70,1548],"class_list":["post-23520","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-gorjeio","tag-grafia","tag-j"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=23520"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23520\/revisions"}],"predecessor-version":[{"id":23521,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23520\/revisions\/23521"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=23520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=23520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=23520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}