{"id":23432,"date":"2020-09-03T11:36:08","date_gmt":"2020-09-03T14:36:08","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=23432"},"modified":"2020-09-03T11:36:27","modified_gmt":"2020-09-03T14:36:27","slug":"anexo-ou-em-anexo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/anexo-ou-em-anexo\/","title":{"rendered":"Anexo ou em anexo? Os dois"},"content":{"rendered":"<p><strong>Anexo<\/strong>, sozinho, \u00e9 adjetivo vira-lata como bonito, feio, rico. Concorda em g\u00eanero e n\u00famero com o substantivo a que se refere: <em>carta anexa, cartas anexas, documento anexo, documentos anexos; crian\u00e7a bonita, objetos bonitos; imagens feias, foto feia, livros feios.<\/em><\/p>\n<p><strong>Em anexo<\/strong> pertence a outra estirpe. \u00c9 adv\u00e9rbio e, portanto, invari\u00e1vel. N\u00e3o tem feminino, masculino, singular ou plural. Com ele \u00e9 tudo igual: <em>A carta segue em anexo. Os documentos est\u00e3o sendo encaminhados em anexo. Em anexo, seguem as foros. Encaminho, em anexo, as notas solicitadas.<br \/>\n<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anexo, sozinho, \u00e9 adjetivo vira-lata como bonito, feio, rico. Concorda em g\u00eanero e n\u00famero com o substantivo a que se refere: carta anexa, cartas anexas, documento anexo, documentos anexos; crian\u00e7a bonita, objetos bonitos; imagens feias, foto feia, livros feios. Em anexo pertence a outra estirpe. \u00c9 adv\u00e9rbio e, portanto, invari\u00e1vel. N\u00e3o tem feminino, masculino, singular ou plural. Com ele \u00e9 tudo igual: A carta segue [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[141,142],"class_list":["post-23432","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-anexo","tag-em-anexo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=23432"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23432\/revisions"}],"predecessor-version":[{"id":23434,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23432\/revisions\/23434"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=23432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=23432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=23432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}