{"id":23333,"date":"2020-08-20T15:42:49","date_gmt":"2020-08-20T18:42:49","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=23333"},"modified":"2020-08-20T17:34:44","modified_gmt":"2020-08-20T20:34:44","slug":"travessao-adeus-duvida","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/travessao-adeus-duvida\/","title":{"rendered":"Travess\u00e3o: adeus, d\u00favida"},"content":{"rendered":"<p>O sinal do travess\u00e3o equivale a dois hifens (\u2014).\u00a0 Use-o:<\/p>\n<p><strong>1.<\/strong> Na introdu\u00e7\u00e3o de di\u00e1logos em geral:<\/p>\n<p><em>Andorinha l\u00e1 fora est\u00e1 dizendo:<\/em><\/p>\n<p><em>\u2014 Passei o dia \u00e0 toa, \u00e0 toa.<\/em><\/p>\n<p><em>Andorinha, andorinha, minha cantiga \u00e9 mais triste!<\/em><\/p>\n<p><em>Passei a vida \u00e0 toa, \u00e0 toa.<\/em><\/p>\n<p>(Manuel Bandeira)<\/p>\n<p><strong>2.<\/strong> Na separa\u00e7\u00e3o das datas de nascimento e morte de uma pessoa:<\/p>\n<p><em>Recife, 1908 \u2014 Bras\u00edlia, 1962.<\/em><\/p>\n<p><strong>3.<\/strong> No destaque de palavra ou express\u00e3o no interior de uma frase (no caso, \u00e9 usado duplamente):<\/p>\n<p><em>O candidato conseguiu \u2013 at\u00e9 \u2013 o aplauso dos advers\u00e1rios<\/em>.<\/p>\n<p><strong>4.<\/strong> No lugar dos dois pontos ao introduzir uma enumera\u00e7\u00e3o. Compare:<\/p>\n<p>Na feira, comprou as frutas habituais: banana, ma\u00e7\u00e3, laranja, pera e melancia.<\/p>\n<p>Na feira, comprou as frutas habituais \u2014 banana, ma\u00e7\u00e3, laranja, pera e melancia.<\/p>\n<p><strong>5.<\/strong> Na substitui\u00e7\u00e3o da v\u00edrgula nos apostos. Compare:<\/p>\n<p><em>Bras\u00edlia, a capital do Brasil, fica no Planalto Central.<\/em><\/p>\n<p><em>Bras\u00edlia \u2014 a capital do Brasil \u2014 fica no Planalto Central.<\/em><\/p>\n<p><strong>Modera\u00e7\u00e3o<\/strong><\/p>\n<p>N\u00e3o abuse do travess\u00e3o. Ele grita na frase. Um por par\u00e1grafo \u00e9 pra l\u00e1 de suficiente.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O sinal do travess\u00e3o equivale a dois hifens (\u2014).\u00a0 Use-o: 1. Na introdu\u00e7\u00e3o de di\u00e1logos em geral: Andorinha l\u00e1 fora est\u00e1 dizendo: \u2014 Passei o dia \u00e0 toa, \u00e0 toa. Andorinha, andorinha, minha cantiga \u00e9 mais triste! Passei a vida \u00e0 toa, \u00e0 toa. (Manuel Bandeira) 2. Na separa\u00e7\u00e3o das datas de nascimento e morte de uma pessoa: Recife, 1908 \u2014 Bras\u00edlia, 1962. 3. No [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[2104],"class_list":["post-23333","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-travessao"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=23333"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23333\/revisions"}],"predecessor-version":[{"id":23336,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23333\/revisions\/23336"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=23333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=23333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=23333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}