{"id":23221,"date":"2020-08-07T08:56:57","date_gmt":"2020-08-07T11:56:57","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=23221"},"modified":"2020-08-07T08:56:57","modified_gmt":"2020-08-07T11:56:57","slug":"acento-que","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/acento-que\/","title":{"rendered":"Acento: qu\u00ea"},"content":{"rendered":"<p><strong>Que<\/strong> sem acento ou <strong>que<\/strong> com acento? Quase sempre sem. O acento se usa em duas ocasi\u00f5es. Uma: quando <strong>o que<\/strong> \u00e9 substantivo. A\u00ed, como bom substantivo, tem plural.<\/p>\n<p>Os atores t\u00eam um qu\u00ea especial.<\/p>\n<p>Dois qu\u00eas me chamam a aten\u00e7\u00e3o.<\/p>\n<p>O professor manda cortar os qu\u00eas da reda\u00e7\u00e3o.<\/p>\n<p>Tamb\u00e9m tem acento quando est\u00e1 no fim da frase, no fim mesmo, colado no ponto:<\/p>\n<p>Voc\u00ea disse o qu\u00ea?<\/p>\n<p>Qu\u00ea? Explique melhor.<\/p>\n<p>O qu\u00ea? Uau! Que luxo!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que sem acento ou que com acento? Quase sempre sem. O acento se usa em duas ocasi\u00f5es. Uma: quando o que \u00e9 substantivo. A\u00ed, como bom substantivo, tem plural. Os atores t\u00eam um qu\u00ea especial. Dois qu\u00eas me chamam a aten\u00e7\u00e3o. O professor manda cortar os qu\u00eas da reda\u00e7\u00e3o. Tamb\u00e9m tem acento quando est\u00e1 no fim da frase, no fim mesmo, colado no ponto: Voc\u00ea [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[240,11],"class_list":["post-23221","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-acentuacao-grafica","tag-que"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=23221"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23221\/revisions"}],"predecessor-version":[{"id":23222,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23221\/revisions\/23222"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=23221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=23221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=23221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}