{"id":23149,"date":"2020-07-29T11:47:29","date_gmt":"2020-07-29T14:47:29","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=23149"},"modified":"2020-07-29T11:47:29","modified_gmt":"2020-07-29T14:47:29","slug":"veja-maltrata-a-concordancia","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/veja-maltrata-a-concordancia\/","title":{"rendered":"Veja maltrata a concord\u00e2ncia"},"content":{"rendered":"<p>A <em>Veja SP<\/em> escreveu: &#8220;O mapeamento aponta que 1,32 milh\u00f5es de pessoas foram infectadas&#8221;. Deu a informa\u00e7\u00e3o, mas maltratou a l\u00edngua. A concord\u00e2ncia de milh\u00e3o, bilh\u00e3o, trilh\u00e3o &amp; cia. se faz com o n\u00famero que vem antes da v\u00edrgula: <em>1, 32 milh\u00e3o, 1,58 bilh\u00e3o, 2,1 trilh\u00f5es, 10,35 milh\u00f5es<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Veja SP escreveu: &#8220;O mapeamento aponta que 1,32 milh\u00f5es de pessoas foram infectadas&#8221;. Deu a informa\u00e7\u00e3o, mas maltratou a l\u00edngua. A concord\u00e2ncia de milh\u00e3o, bilh\u00e3o, trilh\u00e3o &amp; cia. se faz com o n\u00famero que vem antes da v\u00edrgula: 1, 32 milh\u00e3o, 1,58 bilh\u00e3o, 2,1 trilh\u00f5es, 10,35 milh\u00f5es.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[235,880,4708],"class_list":["post-23149","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-concordancia","tag-milhao","tag-veja-sp"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=23149"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23149\/revisions"}],"predecessor-version":[{"id":23150,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/23149\/revisions\/23150"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=23149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=23149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=23149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}