{"id":22940,"date":"2020-07-09T11:32:47","date_gmt":"2020-07-09T14:32:47","guid":{"rendered":"http:\/\/blogs.correiobraziliense.com.br\/dad\/?p=22940"},"modified":"2020-07-09T11:32:47","modified_gmt":"2020-07-09T14:32:47","slug":"estadao-omite-virgula-e-confunde","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/estadao-omite-virgula-e-confunde\/","title":{"rendered":"Estad\u00e3o omite v\u00edrgula e confunde"},"content":{"rendered":"<p>Manchete do site do <em>Estad\u00e3o<\/em>: &#8220;Recursos foram doados pela Noruega e Alemanha para o Ibama combater inc\u00eandios e For\u00e7a Nacional ampliar a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o&#8221;. Reparou? Leitura r\u00e1pida d\u00e1 a impress\u00e3o de que o Ibama deveria combater inc\u00eandios e a For\u00e7a Nacional.<\/p>\n<p>Raz\u00e3o do duplo entendimento: a aus\u00eancia da v\u00edrgula. A conjun\u00e7\u00e3o <strong>e<\/strong> liga ora\u00e7\u00f5es com sujeitos diferentes que permitem a confus\u00e3o:<\/p>\n<p>Recursos foram doados pela Noruega e Alemanha \/ para o Ibama combater inc\u00eandios \/ <strong>e<\/strong> For\u00e7a Nacional ampliar a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o.<\/p>\n<p>A sa\u00edda? O sinalzinho na separa\u00e7\u00e3o das ora\u00e7\u00f5es:<\/p>\n<p>Recursos foram doados pela Noruega e Alemanha para o Ibama combater inc\u00eandios<strong>,<\/strong> e For\u00e7a Nacional ampliar a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o.<\/p>\n<p>Oba! O leitor agradece.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manchete do site do Estad\u00e3o: &#8220;Recursos foram doados pela Noruega e Alemanha para o Ibama combater inc\u00eandios e For\u00e7a Nacional ampliar a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o&#8221;. Reparou? Leitura r\u00e1pida d\u00e1 a impress\u00e3o de que o Ibama deveria combater inc\u00eandios e a For\u00e7a Nacional. Raz\u00e3o do duplo entendimento: a aus\u00eancia da v\u00edrgula. A conjun\u00e7\u00e3o e liga ora\u00e7\u00f5es com sujeitos diferentes que permitem a confus\u00e3o: Recursos foram doados pela [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[98,2730,4631,5],"class_list":["post-22940","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-e","tag-estadao","tag-sujeitos-diferentes","tag-virgula"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=22940"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22940\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=22940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=22940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=22940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}